{"id":10229,"date":"2025-12-29T03:03:45","date_gmt":"2025-12-28T20:03:45","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=10229"},"modified":"2026-01-09T03:28:44","modified_gmt":"2026-01-08T20:28:44","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af-%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%97%e0%b8%b4%e0%b8%99-%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b8%8a%e0%b8%a1%e0%b8%87%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/12\/29\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af-%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%97%e0%b8%b4%e0%b8%99-%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b8%8a%e0%b8%a1%e0%b8%87%e0%b8%b2\/","title":{"rendered":"&#8220;\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19&#8221; \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e07\u0e32\u0e19 OTOP City 2025 \u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e22\u0e2d\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e30\u0e25\u0e38 830 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong>29 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 &#8220;\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19&#8221; \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e07\u0e32\u0e19 OTOP City 2025 \u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e22\u0e2d\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e30\u0e25\u0e38 830 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e1a\u0e1b\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e01\u0e16\u0e39\u0e01\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e41\u0e25\u0e30\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e27\u0e32\u0e19\u0e19\u0e35\u0e49 (28 \u0e18.\u0e04. 68) \u0e40\u0e27\u0e25\u0e32 17.00 \u0e19. <strong>\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e0a\u0e32\u0e0d\u0e27\u0e35\u0e23\u0e01\u0e39\u0e25<\/strong> \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e18\u0e19\u0e19\u0e19\u0e17\u0e4c \u0e19\u0e34\u0e23\u0e32\u0e21\u0e34\u0e29 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e39\u0e48\u0e2a\u0e21\u0e23\u0e2a\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e34\u0e15\u0e15\u0e34\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e07\u0e32\u0e19 OTOP City 2025 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 OTOP \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e13 \u0e0a\u0e32\u0e40\u0e25\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c 1-3 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e47\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1b\u0e32\u0e01\u0e40\u0e01\u0e23\u0e47\u0e14 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e28\u0e34\u0e18\u0e23 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e18\u0e23\u0e01\u0e38\u0e25 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e44\u0e15\u0e23\u0e2a\u0e23\u0e13\u0e01\u0e38\u0e25 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e19\u0e32\u0e07\u0e08\u0e34\u0e13\u0e13\u0e32\u0e23\u0e31\u0e0a\u0e0a\u0e4c \u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e28\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e42\u0e14\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30 \u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 OTOP \u0e43\u0e19\u0e42\u0e0b\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e32\u0e17\u0e34 \u0e42\u0e0b\u0e19 OTOP \u0e0a\u0e27\u0e19\u0e0a\u0e34\u0e21 \u0e42\u0e0b\u0e19\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\u0e43\u0e2a\u0e48\u0e43\u0e2b\u0e49\u0e2a\u0e19\u0e38\u0e01 \u0e42\u0e0b\u0e19\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e32\u0e01\u0e25 \u0e42\u0e0b\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 OTOP \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e1b\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e01\u0e16\u0e39\u0e01\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e21\u0e07\u0e32\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e44\u0e14\u0e49\u0e17\u0e31\u0e01\u0e17\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 OTOP \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e01\u0e16\u0e39\u0e01\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u0e44\u0e14\u0e49\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e28\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e23\u0e49\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e38\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 OTOP \u0e15\u0e48\u0e2d\u0e44\u0e1b<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e2d\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 OTOP \u0e43\u0e19\u0e07\u0e32\u0e19 OTOP CITY 2025 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 &#8211; 28 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 (\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 \u0e18.\u0e04. 68 \u0e40\u0e27\u0e25\u0e32 19.00 \u0e19.) \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 830 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e07\u0e32\u0e19 OTOP CITY \u0e43\u0e19\u0e1b\u0e35 2024 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 20 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e19\u0e34\u0e22\u0e21\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e08\u0e31\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e25\u0e32\u0e19\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e04\u0e0a\u0e32\u0e40\u0e25\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e15\u0e48\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e41\u0e23\u0e01 \u0e15\u0e48\u0e32\u0e07\u0e19\u0e34\u0e22\u0e21\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 OTOP \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e19\u0e25\u0e30\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e2a<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 5 \u0e25\u0e33\u0e14\u0e31\u0e1a\u0e41\u0e23\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1. OTOP 5 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e27\u0e48\u0e32 400 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 2. \u0e42\u0e0b\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 OTOP \u0e01\u0e27\u0e48\u0e32 80 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 3. \u0e42\u0e0b\u0e19 OTOP \u0e0a\u0e27\u0e19\u0e0a\u0e34\u0e21 \u0e01\u0e27\u0e48\u0e32 50 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 4. \u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e01\u0e27\u0e48\u0e32 30 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 5. OTOP Premium \u0e01\u0e27\u0e48\u0e32 25 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/span><\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/to.gsb.or.th\/mIBv9\" rel=\"attachment wp-att-10125\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-10125\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/12\/2048.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/12\/2048.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/12\/2048-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/12\/2048-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>29 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 256&hellip;<\/p>\n","protected":false},"author":2,"featured_media":10230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-10229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=10229"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10229\/revisions"}],"predecessor-version":[{"id":10231,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10229\/revisions\/10231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/10230"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=10229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=10229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=10229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}