{"id":10451,"date":"2026-02-21T06:33:04","date_gmt":"2026-02-20T23:33:04","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=10451"},"modified":"2026-03-02T09:54:41","modified_gmt":"2026-03-02T02:54:41","slug":"%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%97%e0%b8%b4%e0%b8%99-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%87%e0%b8%b2%e0%b8%99-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%99%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2026\/02\/21\/%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%97%e0%b8%b4%e0%b8%99-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%87%e0%b8%b2%e0%b8%99-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%99%e0%b8%84\/","title":{"rendered":"\u201c\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u201d \u200b\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u201c\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e04\u0e35\u0e23\u0e35-\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23\u201d \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22\u0e22\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #0000ff;\"><a class=\"x1i10hfl xjbqb8w x1ejq31n x18oe1m7 x1sy0etr xstzfhl x972fbf x10w94by x1qhh985 x14e42zd x9f619 x1ypdohk xt0psk2 x3ct3a4 xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj xzsf02u x1s688f\" style=\"color: #0000ff;\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZY-Xj-z4HuMugxjB2lYV4LZvmOaVM-1tUKtBs75yUgnSFlPTl_Fgt79xXhdmKJ8O-wABwqdmU_vzMUls1873u97kHtc9afP6CZ0T65MJSxNHU5JMVCYYesirI0Wvu-h8Svgq_ORyE8_R6v9JlBOm0fI&amp;__tn__=-UC%2CP-R\"><span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/a> <\/span>21 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u201c\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u201d \u200b\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22\u0e22\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e30\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e32\u0e2a\u0e38\u0e01 \u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35\u0e01\u0e34\u0e19\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e20\u0e39\u0e21\u0e34\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e22\u0e49\u0e33\u0e44\u0e17\u0e22\u0e04\u0e37\u0e2d\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e1b\u0e25\u0e37\u0e49\u0e21\u0e22\u0e39\u0e40\u0e19\u0e2a\u0e42\u0e01\u0e22\u0e01\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e0b\u0e27\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e37\u0e21\u0e04\u0e33\u0e27\u0e48\u0e32\u0e40\u0e1a\u0e32\u0e2b\u0e27\u0e32\u0e19<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e0a\u0e32\u0e0d\u0e27\u0e35\u0e23\u0e01\u0e39\u0e25<\/strong> \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u201c\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e04\u0e35\u0e23\u0e35-\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23\u201d \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 39 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 \u0e17\u0e35\u0e48\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e04\u0e35\u0e23\u0e35 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35\u0e27\u0e48\u0e32 \u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e43\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32 \u0e43\u0e2b\u0e49 \u0e2a\u0e2a. \u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 3 \u0e04\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e01\u0e23\u0e32\u0e1a\u0e02\u0e2d\u0e1a\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e21\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e15\u0e19\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e14\u0e35\u0e43\u0e08 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e21\u0e32 \u0e41\u0e15\u0e48\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e43\u0e08 \u0e2d\u0e22\u0e32\u0e01\u0e21\u0e32\u0e40\u0e08\u0e2d\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19 \u0e44\u0e21\u0e48\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e21\u0e2d\u0e07\u0e44\u0e1b\u0e17\u0e32\u0e07\u0e0b\u0e49\u0e32\u0e22\u0e01\u0e47\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e02\u0e32\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e1f \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e1a\u0e19\u0e14\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19 \u0e15\u0e19\u0e14\u0e35\u0e43\u0e08\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e41\u0e17\u0e19\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e01 \u0e2d\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e15\u0e19\u0e21\u0e32 \u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e44\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49 \u0e08\u0e30\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e21\u0e32\u0e02\u0e2d\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e02\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e48\u0e32\u0e19\u0e22\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e15\u0e19\u0e08\u0e30\u0e15\u0e34\u0e14\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e32\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e1e\u0e1a\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e22\u0e22\u0e34\u0e49\u0e21 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 \u0e15\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e19\u0e31\u0e48\u0e07\u0e23\u0e16\u0e21\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e22\u0e34\u0e49\u0e21 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01 \u0e04\u0e33\u0e17\u0e31\u0e01\u0e17\u0e32\u0e22 \u0e08\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e2b\u0e22\u0e38\u0e14\u0e23\u0e16\u0e41\u0e25\u0e30\u0e25\u0e07\u0e21\u0e32\u0e17\u0e31\u0e01\u0e17\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e16\u0e44\u0e14\u0e49 \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e44\u0e21\u0e15\u0e23\u0e35\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e20\u0e23\u0e23\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e02\u0e2d\u0e07\u0e1c\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u201d \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e41\u0e25\u0e49\u0e27\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e37\u0e21\u0e04\u0e33\u0e27\u0e48\u0e32\u0e40\u0e1a\u0e32\u0e2b\u0e27\u0e32\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e0a\u0e34\u0e21\u0e02\u0e19\u0e21\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e23\u0e39\u0e49\u0e14\u0e35\u0e27\u0e48\u0e32\u0e04\u0e19\u0e40\u0e23\u0e32\u0e2b\u0e48\u0e27\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e47\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e25\u0e14\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e25\u0e07 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e16\u0e34\u0e48\u0e19\u0e23\u0e2a\u0e40\u0e25\u0e34\u0e28 \u0e22\u0e39\u0e40\u0e19\u0e2a\u0e42\u0e01\u0e22\u0e01\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e17\u0e32\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e25\u0e49\u0e33\u0e04\u0e48\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e48\u0e32\u0e41\u0e01\u0e48\u0e07\u0e01\u0e23\u0e30\u0e08\u0e32\u0e19 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e17\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e21\u0e23\u0e14\u0e01\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e07\u0e23\u0e31\u0e01\u0e20\u0e31\u0e01\u0e14\u0e35\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e0a\u0e38\u0e14\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e14\u0e07\u0e32\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e23\u0e30\u0e1a\u0e38\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e15\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e48\u0e32\u0e08\u0e30\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e32\u0e2a\u0e38\u0e01 \u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e14\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35 \u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e20\u0e39\u0e21\u0e34\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e23\u0e31\u0e01\u0e17\u0e38\u0e01\u0e04\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e20\u0e23\u0e34\u0e22\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48 \u0e2a\u0e2a. \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u201c\u0e23\u0e33\u0e27\u0e07\u0e40\u0e02\u0e32\u0e27\u0e31\u0e07\u201d \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e36\u0e01\u0e04\u0e23\u0e37\u0e49\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e1e\u0e32\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e0a\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e37\u0e48\u0e19\u0e21\u0e37\u0e48\u0e19<\/span><\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/to.gsb.or.th\/kL1e48y\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-10431\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2026\/02\/5000-GSB_highlightpolitics-\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e2b\u0e30-Refinance_600x800px-1.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2026\/02\/5000-GSB_highlightpolitics-\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e2b\u0e30-Refinance_600x800px-1.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2026\/02\/5000-GSB_highlightpolitics-\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e2b\u0e30-Refinance_600x800px-1-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2026\/02\/5000-GSB_highlightpolitics-\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e2b\u0e30-Refinance_600x800px-1-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":10452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38,40],"tags":[],"class_list":["post-10451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38","category-40"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=10451"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10451\/revisions"}],"predecessor-version":[{"id":10453,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/10451\/revisions\/10453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/10452"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=10451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=10451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=10451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}