{"id":1930,"date":"2021-05-05T23:45:30","date_gmt":"2021-05-05T16:45:30","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=1930"},"modified":"2021-10-05T10:13:20","modified_gmt":"2021-10-05T03:13:20","slug":"%e0%b8%a1%e0%b8%b2%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7%e0%b8%8a%e0%b8%b8%e0%b8%94%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88-%e0%b8%84%e0%b8%a3%e0%b8%a1-%e0%b9%81%e0%b8%88%e0%b8%81%e0%b9%80%e0%b8%9e","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2021\/05\/05\/%e0%b8%a1%e0%b8%b2%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7%e0%b8%8a%e0%b8%b8%e0%b8%94%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88-%e0%b8%84%e0%b8%a3%e0%b8%a1-%e0%b9%81%e0%b8%88%e0%b8%81%e0%b9%80%e0%b8%9e\/","title":{"rendered":"\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e0d\u0e48! \u0e04\u0e23\u0e21.\u0e41\u0e08\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21 2,000 \u0e1a\u0e32\u0e17 &#8220;\u0e40\u0e23\u0e32\u0e0a\u0e19\u0e30&#8221; &#8211; &#8220;\u0e2133\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19&#8221; 3,000 \u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e19\u0e25\u0e30\u0e04\u0e23\u0e36\u0e48\u0e07\u0e40\u0e1f\u0e2a 3&#8221;  \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 \u201c\u0e22\u0e34\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e22\u0e34\u0e48\u0e07\u0e44\u0e14\u0e49\u201d 7,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e19"},"content":{"rendered":"\n<p class=\"has-vivid-cyan-blue-color has-text-color\" style=\"font-size:16px\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 : \u0e04\u0e23\u0e21.\u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34\u0e40\u0e1e\u0e34\u0e48\u0e21 2,000 \u0e1a\u0e32\u0e17 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 &#8220;\u0e40\u0e23\u0e32\u0e0a\u0e19\u0e30&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e2133\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19&#8221; \u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a \u201d\u0e04\u0e19\u0e25\u0e30\u0e04\u0e23\u0e36\u0e48\u0e07\u0e40\u0e1f\u0e2a 3\u201d \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e22\u0e34\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e22\u0e34\u0e48\u0e07\u0e44\u0e14\u0e49\u201d \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 E-Voucher 7,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e19<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\" style=\"font-size:16px\">5 \u0e1e.\u0e04.64 <strong>\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0a\u0e32 \u0e1a\u0e39\u0e23\u0e1e\u0e0a\u0e31\u0e22\u0e28\u0e23\u0e35<\/strong> \u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e23\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 85,500 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e02\u0e22\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e15\u0e19\u0e43\u0e19 \u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e21 33 \u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e08\u0e33\u0e19\u0e27\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 9.27 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 18,500 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19 \u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e32\u0e0a\u0e19\u0e30\u201d \u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 32.9&nbsp; \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 67,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 \u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e21 33 \u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d&nbsp; \u0e42\u0e14\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e15\u0e19\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e3233 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e25\u0e30 1,000 \u0e1a\u0e32\u0e17 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 2 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e21\u0e34.\u0e22.2564 \u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\" style=\"font-size:16px\">\u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e22\u0e31\u0e07\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e22\u0e31\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e42\u0e04\u0e27\u0e34\u0e14\u0e04\u0e25\u0e35\u0e48\u0e04\u0e25\u0e32\u0e22\u0e25\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19 140,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e34\u0e01\u0e08\u0e48\u0e32\u0e22\u0e08\u0e32\u0e01 \u0e1e.\u0e23.\u0e01.\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49\u0e2f&nbsp; \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\" style=\"font-size:16px\">1.\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e25\u0e14\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e1a\u0e31\u0e15\u0e23\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e35\u0e48 3&nbsp; \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19&nbsp; 13.65 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e42\u0e14\u0e22\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e25\u0e30 200 \u0e1a\u0e32\u0e17 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 (\u0e01.\u0e04. &#8211; \u0e18.\u0e04.) \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29&nbsp; \u0e08\u0e33\u0e19\u0e27\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 2.4 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e25\u0e30 200 \u0e1a\u0e32\u0e17 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 (\u0e01.\u0e04. &#8211; \u0e18.\u0e04.)<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\" style=\"font-size:16px\">2.\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e42\u0e04\u0e27\u0e34\u0e14-19&nbsp; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23 \u201c\u0e04\u0e19\u0e25\u0e30\u0e04\u0e23\u0e36\u0e48\u0e07\u0e23\u0e30\u0e22\u0e30\u0e17\u0e35\u0e48 3\u201d (Co-pay) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e23\u0e31\u0e10\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 31 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e08\u0e30\u0e2a\u0e21\u0e17\u0e1a\u0e44\u0e14\u0e49\u0e27\u0e31\u0e19\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 150 \u0e1a\u0e32\u0e17 \u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 3,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e22\u0e34\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e22\u0e34\u0e48\u0e07\u0e14\u0e35\u201d \u0e42\u0e14\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 E-Voucher \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 7,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e19&nbsp; \u0e42\u0e14\u0e22\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 E-Voucher \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 \u0e01.\u0e04. &#8211; \u0e18.\u0e04 .2564 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 4 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color\">Advertising<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/04\/600x800-1.jpg\" alt=\"\" class=\"wp-image-1917\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/04\/600x800-1.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/04\/600x800-1-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/04\/600x800-1-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[155,159,156,158,160,157,62,53],"class_list":["post-1930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38","tag-155","tag-159","tag-156","tag-158","tag-160","tag-157","tag-62","tag-53"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/1930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=1930"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/1930\/revisions"}],"predecessor-version":[{"id":1932,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/1930\/revisions\/1932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/1931"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=1930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}