{"id":2301,"date":"2021-10-11T16:32:02","date_gmt":"2021-10-11T09:32:02","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=2301"},"modified":"2021-11-03T23:08:14","modified_gmt":"2021-11-03T16:08:14","slug":"%e0%b8%9c%e0%b8%9a-%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%aa%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2021\/10\/11\/%e0%b8%9c%e0%b8%9a-%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%aa%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2\/","title":{"rendered":"\u0e1c\u0e1a.\u0e01\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e34\u0e19\u0e42\u0e14-\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22"},"content":{"rendered":"\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 : \u0e1c\u0e1a.\u0e01\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e34\u0e19\u0e42\u0e14 &#8211; \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e04\u0e33\u0e19\u0e31\u0e1a \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e22\u0e49\u0e33\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e44\u0e27\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e01\u0e31\u0e19<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">11 \u0e15.\u0e04. 64 <strong>\u0e1e\u0e25.\u0e2d.\u0e04\u0e07\u0e0a\u0e35\u0e1e \u0e15\u0e31\u0e19\u0e15\u0e23\u0e30\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c<\/strong> \u0e42\u0e06\u0e29\u0e01\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 11.00 \u0e19. \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e04\u0e33\u0e19\u0e31\u0e1a\u0e02\u0e2d\u0e07 \u0e1e\u0e25.\u0e23.\u0e2d.John C. Aquilino (\u0e08\u0e2d\u0e2b\u0e4c\u0e19 \u0e0b\u0e35 \u0e2d\u0e32\u0e01\u0e35\u0e25\u0e35\u0e42\u0e19) \u0e1c\u0e1a.\u0e01\u0e01\u0e25.\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e34\u0e19\u0e42\u0e14 \u2013 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e41\u0e02\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e23.\u0e2d.\u0e08\u0e2d\u0e2b\u0e4c\u0e19 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e1c\u0e1a.\u0e01\u0e01\u0e25.\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e34\u0e19\u0e42\u0e14 &#8211; \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 2.5 \u0e25\u0e49\u0e32\u0e19\u0e42\u0e14\u0e2a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 200 \u0e15\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22 \u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e42\u0e04\u0e27\u0e34\u0e14 19 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e23\u0e48\u0e27\u0e21\u0e1c\u0e2a\u0e21 Cobra Gold 2021 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e23\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d \u0e01\u0e2b.\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e39\u0e48\u0e40\u0e08\u0e23\u0e08\u0e32<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u0e41\u0e25\u0e30\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e49\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e22\u0e49\u0e33\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e41\u0e1f\u0e49\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e14\u0e33\u0e23\u0e07\u0e44\u0e27\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e \u0e40\u0e2a\u0e23\u0e35\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31\u0e19<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color\">Advertising<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800.jpg\" alt=\"\" class=\"wp-image-2214\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[41,37],"tags":[340,342,151,341,53],"class_list":["post-2301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-37","tag-340","tag-342","tag-----2","tag-341","tag-53"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=2301"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2301\/revisions"}],"predecessor-version":[{"id":2303,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2301\/revisions\/2303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/2302"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=2301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=2301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=2301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}