{"id":2343,"date":"2021-10-26T14:10:00","date_gmt":"2021-10-26T07:10:00","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=2343"},"modified":"2021-11-03T23:07:52","modified_gmt":"2021-11-03T16:07:52","slug":"%e0%b8%88%e0%b8%b8%e0%b8%a3%e0%b8%b4%e0%b8%99%e0%b8%97%e0%b8%a3%e0%b9%8c-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b8%9e%e0%b8%ad%e0%b9%83%e0%b8%88%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b9%80%e0%b8%a5%e0%b8%82%e0%b8%aa","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2021\/10\/26\/%e0%b8%88%e0%b8%b8%e0%b8%a3%e0%b8%b4%e0%b8%99%e0%b8%97%e0%b8%a3%e0%b9%8c-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b8%9e%e0%b8%ad%e0%b9%83%e0%b8%88%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b9%80%e0%b8%a5%e0%b8%82%e0%b8%aa\/","title":{"rendered":"\u0e08\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e1c\u0e22\u0e1e\u0e2d\u0e43\u0e08\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 9 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27 15.5% \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 6 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17"},"content":{"rendered":"\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 : \u0e08\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e1c\u0e22\u0e1e\u0e2d\u0e43\u0e08\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 9 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27 15.5% \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e01.\u0e22. \u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27 17.7% \u0e22\u0e49\u0e33\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1c\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">26 \u0e15.\u0e04. 64 <strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e31\u0e0a\u0e14\u0e32 \u0e18\u0e19\u0e32\u0e14\u0e34\u0e40\u0e23\u0e01<\/strong> \u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 <strong>\u0e19\u0e32\u0e22\u0e08\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e25\u0e31\u0e01\u0e29\u0e13\u0e27\u0e34\u0e28\u0e34\u0e29\u0e0f\u0e4c<\/strong> \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 9 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27 15.5% \u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 6,202,170 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27 17.1% \u0e23\u0e32\u0e27 760,556 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19 12.9% \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23 11.3% \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 15.8% \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1. \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e17\u0e34 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 15,138 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e25\u0e33\u0e44\u0e22\u0e2a\u0e14 1,967 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2a\u0e14 152 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 10,432 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e02\u0e49\u0e32\u0e27 10,867 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 2. \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e17\u0e34 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b 5,015 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 6,818 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 3. \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e32\u0e17\u0e34 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 91,585 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01 20,302 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a 26,507 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a 73,911 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<strong><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e22\u0e31\u0e07\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e17\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e25\u0e01\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 WTO \u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e25\u0e01 +10.8% \u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e44\u0e27\u0e49 +8.0% \u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e1a\u0e32\u0e17\u0e22\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e2d\u0e48\u0e2d\u0e19\u0e04\u0e48\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e14\u0e49\u0e32\u0e19\u0e23\u0e32\u0e04\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e22\u0e31\u0e07\u0e22\u0e49\u0e33\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e19\u0e49\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e15\u0e48\u0e32\u0e07\u0e46<strong><\/strong><\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color\">Advertising<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800.jpg\" alt=\"\" class=\"wp-image-2214\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2021\/10\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[374,373,375,53],"class_list":["post-2343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48","tag-374","tag-373","tag-375","tag-53"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=2343"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2343\/revisions"}],"predecessor-version":[{"id":2345,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2343\/revisions\/2345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/2344"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=2343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=2343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=2343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}