{"id":2772,"date":"2022-02-12T22:59:57","date_gmt":"2022-02-12T15:59:57","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=2772"},"modified":"2022-02-13T23:09:25","modified_gmt":"2022-02-13T16:09:25","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b9%80%e0%b8%94%e0%b8%b4%e0%b8%99%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b9%81%e0%b8%81%e0%b9%89%e0%b8%9b%e0%b8%b1%e0%b8%8d%e0%b8%ab%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/02\/12\/%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b9%80%e0%b8%94%e0%b8%b4%e0%b8%99%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b9%81%e0%b8%81%e0%b9%89%e0%b8%9b%e0%b8%b1%e0%b8%8d%e0%b8%ab%e0%b8%b2\/","title":{"rendered":"\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07 PM2.5 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e35 65 \u0e43\u0e0a\u0e49\u0e2b\u0e25\u0e31\u0e01 \u201c1 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 5 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 3 \u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e40\u0e2b\u0e15\u0e38\u201d"},"content":{"rendered":"<p><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><strong>\u00a0<\/strong><strong>: \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07 <\/strong><strong>PM<\/strong><strong>2.5 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e35 65 \u0e43\u0e0a\u0e49\u0e2b\u0e25\u0e31\u0e01 \u201c1 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 5 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 3 \u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e40\u0e2b\u0e15\u0e38\u201d<\/strong><\/p>\n<p>12 \u0e01.\u0e1e. 65 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 PM2.5 \u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e35\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e43\u0e19\u0e1b\u0e35 64 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2b\u0e32\u0e01\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e1b\u0e35 63 \u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d 17 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e25\u0e14\u0e25\u0e07 8 &#8211; 9%<\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e35 65 \u0e01\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e14\u0e49\u0e32\u0e19\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c1 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 5 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 3 \u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e40\u0e2b\u0e15\u0e38\u201d \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n<p>1.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 PM2.5 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 7 \u0e27\u0e31\u0e19, \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48, \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07<\/p>\n<p>2.\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 3,000 \u0e15\u0e31\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e17\u0e28\u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c<\/p>\n<p>3.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e16\u0e04\u0e27\u0e31\u0e19\u0e14\u0e33\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e04\u0e27\u0e31\u0e19\u0e14\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/p>\n<p>4.\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a One Voice One Team \u0e1c\u0e48\u0e32\u0e19 4 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 On Air, Online, On Ground \u0e41\u0e25\u0e30 On influ\u2019s<\/p>\n<p>5.\u0e40\u0e08\u0e23\u0e08\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e17\u0e27\u0e34\u0e20\u0e32\u0e04\u0e35 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e44\u0e01\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e23\u0e48\u0e27\u0e21 ASEAN Joint KPI \u0e25\u0e14\u0e08\u0e38\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 20%<\/p>\n<p>6.\u0e02\u0e22\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01 10 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e1b\u0e35 2565 \u0e08\u0e30\u0e21\u0e35\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e43\u0e19 56 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14<\/p>\n<p>7.\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e02\u0e15\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1b\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e2b\u0e49\u0e32\u0e21\u0e40\u0e1c\u0e32\u0e40\u0e14\u0e47\u0e14\u0e02\u0e32\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e23\u0e27\u0e21 4,150 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e1f\u0e1b\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e27\u0e19 1,615 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19<\/p>\n<p>\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e43\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e1d\u0e38\u0e48\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e02\u0e19\u0e32\u0e14\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 2.5 \u0e44\u0e21\u0e04\u0e23\u0e2d\u0e19 (PM2.5) \u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e25\u0e14\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49<\/p>\n<p>\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Air4Thai.com \u0e41\u0e25\u0e30 bangkokairquality.com \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 Air4Thai \u0e41\u0e25\u0e30 AirBKK<\/p>\n<p>Advertising<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg\" data-rel=\"penci-gallery-image-content\" ><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2717 size-full\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-2772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=2772"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2772\/revisions"}],"predecessor-version":[{"id":2774,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2772\/revisions\/2774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/2773"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=2772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=2772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=2772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}