{"id":2778,"date":"2022-02-14T21:02:08","date_gmt":"2022-02-14T14:02:08","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=2778"},"modified":"2022-02-14T21:02:08","modified_gmt":"2022-02-14T14:02:08","slug":"%e0%b9%80%e0%b8%a5%e0%b8%82%e0%b8%b2%e0%b8%af-%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b8%b4%e0%b8%9a%e0%b8%b2%e0%b8%95%e0%b8%a1%e0%b8%b8","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/02\/14\/%e0%b9%80%e0%b8%a5%e0%b8%82%e0%b8%b2%e0%b8%af-%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b1%e0%b8%99%e0%b8%99%e0%b8%b4%e0%b8%9a%e0%b8%b2%e0%b8%95%e0%b8%a1%e0%b8%b8\/","title":{"rendered":"\u0e40\u0e25\u0e02\u0e32\u0e2f \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21\u0e42\u0e25\u0e01 \u0e40\u0e02\u0e49\u0e32\u0e1e\u0e1a \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e1e\u0e2b\u0e38\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22"},"content":{"rendered":"<p><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><strong>\u00a0<\/strong><strong>: \u0e40\u0e25\u0e02\u0e32\u0e2f \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21\u0e42\u0e25\u0e01 \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e1e\u0e2b\u0e38\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 <\/strong><\/p>\n<p>14 \u0e01.\u0e1e. 65 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e14\u0e23.\u0e21\u0e38\u0e2e\u0e31\u0e21\u0e21\u0e31\u0e14 \u0e1a\u0e34\u0e19 \u0e2d\u0e31\u0e1a\u0e14\u0e38\u0e25\u0e01\u0e30\u0e23\u0e35\u0e21 \u0e2d\u0e31\u0e25\u0e2d\u0e35\u0e0b\u0e32 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21\u0e42\u0e25\u0e01 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e04\u0e32\u0e23\u0e27\u0e30 \u0e1e\u0e25\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30 \u0e23\u0e21\u0e27.\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e13 \u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25<\/p>\n<p>\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e34\u0e19\u0e14\u0e35\u0e17\u0e35\u0e48\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21\u0e42\u0e25\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e35\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e2a\u0e25\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e0b\u0e32\u0e2d\u0e38\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e1b\u0e0f\u0e34\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e34\u0e01\u0e0a\u0e19\u0e15\u0e48\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32<\/p>\n<p>\u0e44\u0e17\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21\u0e42\u0e25\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e21\u0e19\u0e38\u0e29\u0e22\u0e18\u0e23\u0e23\u0e21\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32\u0e2d\u0e34\u0e2a\u0e25\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e08\u0e36\u0e07\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2f \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e33\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e48\u0e19\u0e41\u0e1f\u0e49\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e44\u0e17\u0e22\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21<\/p>\n<p>\u0e14\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2f \u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e35\u0e08\u0e38\u0e14\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e21\u0e35\u0e1b\u0e0f\u0e34\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e1e\u0e2b\u0e38\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e44\u0e21\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e02\u0e49\u0e2d\u0e02\u0e31\u0e14\u0e41\u0e22\u0e49\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 3 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e28\u0e32\u0e2a\u0e19\u0e32\u0e41\u0e25\u0e30\u0e28\u0e35\u0e25\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e2d\u0e07\u0e14\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1e\u0e2b\u0e38\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>Advertising<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg\" data-rel=\"penci-gallery-image-content\" ><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2717 size-full\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/02\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-2778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-50"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=2778"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2778\/revisions"}],"predecessor-version":[{"id":2780,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2778\/revisions\/2780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/2779"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=2778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=2778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=2778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}