{"id":2926,"date":"2022-03-17T23:25:13","date_gmt":"2022-03-17T16:25:13","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=2926"},"modified":"2022-03-17T23:25:13","modified_gmt":"2022-03-17T16:25:13","slug":"%e0%b8%aa%e0%b8%98-%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad-%e0%b8%a8%e0%b8%9a%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/03\/17\/%e0%b8%aa%e0%b8%98-%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad-%e0%b8%a8%e0%b8%9a%e0%b8%84\/","title":{"rendered":"\u0e2a\u0e18. \u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e19\u0e2d \u0e28\u0e1a\u0e04. \u0e43\u0e2b\u0e49\u0e16\u0e2d\u0e14\u0e41\u0e21\u0e2a\u0e01\u0e4c\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e44\u0e14\u0e49"},"content":{"rendered":"<p><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><strong>\u00a0<\/strong><strong>: <\/strong><strong>\u0e2a\u0e18. \u0e41\u0e08\u0e07 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e19\u0e2d \u0e28\u0e1a\u0e04. \u0e16\u0e2d\u0e14\u0e41\u0e21\u0e2a\u0e01\u0e4c\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30<\/strong> <strong>\u0e41\u0e15\u0e48\u0e0a\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23 <\/strong><strong>Test&amp;Go <\/strong><strong>\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07<\/strong><\/p>\n<p>17 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2565 <strong>\u0e19\u0e1e.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e20\u0e39\u0e21\u0e34 \u0e27\u0e07\u0e28\u0e4c\u0e23\u0e08\u0e34\u0e15<\/strong> \u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07 \u0e01\u0e23\u0e13\u0e35\u0e21\u0e35\u0e02\u0e48\u0e32\u0e27 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e19\u0e2d \u0e28\u0e1a\u0e04.\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e2d\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e27\u0e48\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1c\u0e34\u0e14<\/p>\n<p>\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e47\u0e08\u0e08\u0e23\u0e34\u0e07 \u0e04\u0e37\u0e2d \u0e2a\u0e18. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e19\u0e2d \u0e28\u0e1a\u0e04. \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a Test &amp;Go \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e2b\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35 RT-PCR \u0e20\u0e32\u0e22\u0e43\u0e19 72 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e27\u0e08 RT-PCR \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08 ATK \u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e0b\u0e49\u0e33\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e2b\u0e25\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e40\u0e2b\u0e25\u0e37\u0e2d 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2f \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e28\u0e1a\u0e04.\u0e0a\u0e38\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e42\u0e04\u0e27\u0e34\u0e14 19 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e42\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e16\u0e34\u0e48\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e28\u0e1a\u0e04.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e21\u0e34\u0e15\u0e34\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e01\u0e31\u0e19<\/p>\n<p>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e42\u0e04\u0e27\u0e34\u0e14 19 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e0a\u0e48\u0e27\u0e07 Post Pandemic \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 4 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e17\u0e22\u0e2d\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e49\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e21\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e41\u0e15\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e27\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e48\u0e27\u0e22\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e27\u0e21 \u0e2a\u0e48\u0e27\u0e19\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2d\u0e32\u0e08\u0e43\u0e2b\u0e49\u0e16\u0e2d\u0e14\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e48\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e17\u0e33\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e33\u0e19\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e19\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e41\u0e1c\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e25\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e08\u0e19\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e21\u0e48<\/p>\n<p>\u201c\u0e02\u0e2d\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d \u0e28\u0e1a\u0e04. \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e16\u0e2d\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e42\u0e23\u0e04\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e16\u0e34\u0e48\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32\u201d<\/p>\n<p>Advertising<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/03\/600x800-2.jpg\" data-rel=\"penci-gallery-image-content\" ><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2886 size-full\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/03\/600x800-2.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/03\/600x800-2.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/03\/600x800-2-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/03\/600x800-2-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-2926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=2926"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2926\/revisions"}],"predecessor-version":[{"id":2928,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/2926\/revisions\/2928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/2927"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=2926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=2926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=2926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}