{"id":3709,"date":"2022-07-26T21:23:33","date_gmt":"2022-07-26T14:23:33","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=3709"},"modified":"2022-08-05T14:35:09","modified_gmt":"2022-08-05T07:35:09","slug":"%e0%b8%aa%e0%b8%a1%e0%b8%8a%e0%b8%b1%e0%b8%a2-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b9%80%e0%b8%ad%e0%b8%b2%e0%b8%aa%e0%b8%b9%e0%b8%95","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/07\/26\/%e0%b8%aa%e0%b8%a1%e0%b8%8a%e0%b8%b1%e0%b8%a2-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b9%80%e0%b8%ad%e0%b8%b2%e0%b8%aa%e0%b8%b9%e0%b8%95\/","title":{"rendered":"\u201c\u0e2a\u0e21\u0e0a\u0e31\u0e22\u201d \u0e40\u0e1c\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e2d\u0e32\u0e2a\u0e39\u0e15\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e2b\u0e32\u0e23 100 \u0e04\u0e37\u0e19"},"content":{"rendered":"<p><span style=\"font-size: 20px; color: #993300;\"><strong>\u21d2 \u201c\u0e2a\u0e21\u0e0a\u0e31\u0e22\u201d \u0e40\u0e1c\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e2d\u0e32\u0e2a\u0e39\u0e15\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e2b\u0e32\u0e23 100 \u0e04\u0e37\u0e19<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #993300;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span> : 26 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2565 \u201c\u0e2a\u0e21\u0e0a\u0e31\u0e22\u201d \u0e0a\u0e35\u0e49\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e25\u0e39\u0e01\u0e40\u0e23\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e31\u0e14\u0e41\u0e23\u0e01\u0e04\u0e48\u0e33\u0e19\u0e35\u0e49 \u0e40\u0e1c\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e2d\u0e32\u0e2a\u0e39\u0e15\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e2a.\u0e2a.\u0e1a\u0e0a.\u0e2b\u0e32\u0e23 100 \u0e04\u0e37\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32 \u0e41\u0e04\u0e48\u0e22\u0e37\u0e49\u0e2d\u0e40\u0e27\u0e25\u0e32\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e27\u0e32\u0e23\u0e30\u00a0 3 \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e22\u00a0 15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e23\u0e48\u0e32\u0e07\u0e15\u0e01\u0e44\u0e1b\u00a0\u00a0 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48 \u0e04\u0e23\u0e21.\u0e40\u0e2a\u0e19\u0e2d<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e0a\u0e31\u0e22\u00a0\u00a0 \u0e28\u0e23\u0e35\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e22\u0e32\u0e01\u0e23<\/strong>\u00a0\u00a0 \u0e42\u0e06\u0e29\u0e01\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 (\u0e01\u0e21\u0e18.) \u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e23\u0e48\u0e32\u0e07 \u0e1e.\u0e23.\u0e1b.\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 (\u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48\u2026) \u0e1e.\u0e28. \u2026 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04\u00a0 \u0e01\u0e23\u0e13\u0e35\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32\u0e21\u0e35\u0e21\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e01\u0e49\u0e44\u0e02\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e2a.\u0e2a. \u0e16\u0e2d\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e2b\u0e21\u0e48\u00a0 \u0e27\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e21\u0e32\u0e15\u0e23\u0e32\u0e43\u0e14\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e23 500\u00a0 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e2a.\u0e2a. \u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e1b\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u00a0 \u0e23\u0e48\u0e32\u0e07 \u0e1e.\u0e23.\u0e1b. \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e2a.\u0e2a. \u0e08\u0e36\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2f \u0e17\u0e35\u0e48\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e1b\u0e34\u0e15\u0e38\u0e40\u0e15\u0e0a\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u00a0 \u0e01\u0e21\u0e18. \u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 \u0e1e.\u0e23.\u0e1b. \u0e42\u0e14\u0e22\u0e40\u0e23\u0e47\u0e27 \u00a0\u0e42\u0e14\u0e22\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e01\u0e31\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35\u0e04\u0e37\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e25\u0e32 19.00 \u0e19. \u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e01\u0e21\u0e18. \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e1a\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e21\u0e15\u0e34\u0e27\u0e32\u0e23\u0e30\u0e17\u0e35\u0e48 3 \u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2565 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e40\u0e27\u0e25\u0e32 180 \u0e27\u0e31\u0e19\u00a0 \u0e19\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e23\u0e48\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e20\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e48\u0e32\u0e19\u0e27\u0e32\u0e23\u0e30\u0e17\u0e35\u0e48 3\u00a0 \u0e20\u0e32\u0e22\u0e43\u0e19 15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2565 \u0e23\u0e48\u0e32\u0e07 \u0e1e.\u0e23.\u0e1b.\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32\u0e08\u0e30\u0e15\u0e01\u0e44\u0e1b \u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e32\u0e07\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48 \u0e04\u0e23\u0e21. \u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 \u0e04\u0e37\u0e2d\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e32\u0e23 100\u00a0 \u0e42\u0e14\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e22\u0e37\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 180 \u0e27\u0e31\u0e19\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e07\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e2b\u0e32\u0e23 100 \u0e04\u0e37\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07 \u0e01\u0e01\u0e15. \u0e2b\u0e23\u0e37\u0e2d\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e43\u0e2b\u0e49\u0e22\u0e37\u0e14\u0e40\u0e22\u0e37\u0e49\u0e2d\u00a0 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e32\u0e23 100 \u0e04\u0e37\u0e19\u0e21\u0e32\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e23\u0e07\u0e21\u0e32\u0e01 \u0e2b\u0e32\u0e01\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e01\u0e47\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e23\u0e04\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49 \u0e2a.\u0e2a.\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e2d\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e33 \u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e44\u0e21\u0e48\u0e21\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e23\u00a0 \u0e41\u0e04\u0e48 40-45 \u0e04\u0e19\u0e43\u0e19 100 \u0e04\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/span><\/p>\n<p><span style=\"color: #993300;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/600x800-14\/\" rel=\"attachment wp-att-3614\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3614\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/07\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/07\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/07\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/07\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u201c\u0e2a\u0e21\u0e0a\u0e31\u0e22\u201d \u0e40\u0e1c\u0e22\u0e40&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,39],"tags":[],"class_list":["post-3709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-39"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":2,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"predecessor-version":[{"id":3712,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3709\/revisions\/3712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/3710"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}