{"id":3890,"date":"2022-09-12T12:41:59","date_gmt":"2022-09-12T05:41:59","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=3890"},"modified":"2022-10-16T14:56:02","modified_gmt":"2022-10-16T07:56:02","slug":"%e0%b8%9e%e0%b8%a5-%e0%b8%ad-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%95%e0%b8%a3-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%94%e0%b8%b4%e0%b8%99","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/09\/12\/%e0%b8%9e%e0%b8%a5-%e0%b8%ad-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%95%e0%b8%a3-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%94%e0%b8%b4%e0%b8%99\/","title":{"rendered":"\u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e21\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e17\u0e33\u0e01\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48 \u0e08.\u0e15\u0e32\u0e01"},"content":{"rendered":"<p><span style=\"color: #993300;\"><strong><span style=\"font-size: 20px;\">\u21d2 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e21\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e17\u0e33\u0e01\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48 \u0e08.\u0e15\u0e32\u0e01<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #993300;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span> : 12 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2565 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08.\u0e15\u0e32\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e19\u0e27\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e17\u0e33\u0e01\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e27\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13<\/strong> \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e32\u0e22\u0e0a\u0e31\u0e22\u0e27\u0e38\u0e12\u0e34 \u0e18\u0e19\u0e32\u0e04\u0e21\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u00a0 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e17\u0e2b\u0e32\u0e23 2 \u0e01\u0e2d\u0e07\u0e1a\u0e34\u0e19 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e44\u0e1b\u0e22\u0e31\u0e07 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08.\u0e15\u0e32\u0e01 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e23\u0e27\u0e08\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e49\u0e33\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e21\u0e17\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e1a\u0e17\u0e35\u0e48 14 \u0e15.\u0e41\u0e21\u0e48\u0e1b\u0e30 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08.\u0e15\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u201c\u0e1a\u0e08\u0e18.\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e21\u0e2d\u0e1a\u0e2a\u0e38\u0e02\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e17\u0e33\u0e14\u0e34\u0e19\u201d \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1b\u0e48\u0e32\u0e2a\u0e07\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e2a\u0e21\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e15\u0e31\u0e27\u0e1c\u0e39\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u0e01\u0e34\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 (\u0e04\u0e17\u0e0a.) \u0e42\u0e14\u0e22\u0e21\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1b\u0e48\u0e32\u0e2a\u0e07\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e08\u0e33\u0e19\u0e27\u0e19 5 \u0e1b\u0e48\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u201c\u0e1b\u0e48\u0e32\u0e0a\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e1a\u0e41\u0e25\u0e30\u0e1b\u0e48\u0e32\u0e41\u0e21\u0e48\u0e42\u0e01\u0e19\u0e40\u0e01\u0e19\u201d \u201c\u0e1b\u0e48\u0e32\u0e41\u0e21\u0e48\u0e25\u0e30\u0e40\u0e21\u0e32\u201d \u201c\u0e1b\u0e48\u0e32\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14\u201d \u201c\u0e1b\u0e48\u0e32\u0e17\u0e48\u0e32\u0e2a\u0e2d\u0e07\u0e22\u0e32\u0e07\u201d \u0e41\u0e25\u0e30 \u201c\u0e1b\u0e48\u0e32\u0e41\u0e21\u0e48\u0e23\u0e30\u0e01\u0e32\u201d \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e21\u0e2d\u0e1a\u0e2a\u0e21\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e15\u0e31\u0e27\u0e1c\u0e39\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e01\u0e34\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e15\u0e32\u0e01 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e48\u0e32\u0e0a\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e1a\u0e41\u0e25\u0e30\u0e1b\u0e48\u0e32\u0e41\u0e21\u0e48\u0e42\u0e01\u0e19\u0e40\u0e01\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 1,231 \u0e40\u0e25\u0e48\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e1b\u0e30 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e15\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e27\u0e19 43 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e08\u0e18. \u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 58 \u0e44\u0e23\u0e48\u0e40\u0e28\u0e29 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u201c\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14\u201d \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19 1 \u0e1b\u0e35\u0e40\u0e28\u0e29 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e21\u0e35\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07 (Best Practice) \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e1a\u0e08\u0e18. \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u00a0 \u0e1c\u0e39\u0e49\u0e22\u0e32\u0e01\u0e08\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e19\u0e49\u0e33\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e01\u0e19\u0e0a.) \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e01\u0e2d\u0e19\u0e0a.) \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e15.\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e1c\u0e32\u0e41\u0e14\u0e07 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08.\u0e15\u0e32\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e1a\u0e1b\u0e30\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/span><\/p>\n<p><span style=\"color: #993300;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%97%e0%b8%b8%e0%b8%81%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87\/600x800-15\/\" rel=\"attachment wp-att-3881\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3881\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/09\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/09\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/09\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/09\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-3890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=3890"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3890\/revisions"}],"predecessor-version":[{"id":3892,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/3890\/revisions\/3892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/3891"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=3890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=3890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=3890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}