{"id":4089,"date":"2022-10-13T22:16:36","date_gmt":"2022-10-13T15:16:36","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4089"},"modified":"2022-11-06T22:23:10","modified_gmt":"2022-11-06T15:23:10","slug":"%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/","title":{"rendered":"\u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e23\u0e07\u0e40\u0e1b\u0e34\u0e14 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9"},"content":{"rendered":"<p><span style=\"font-size: 20px; color: #993300;\"><strong>\u21d2 \u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e23\u0e07\u0e40\u0e1b\u0e34\u0e14 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2f \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35 \u0e40\u0e2a\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e44\u0e1b\u0e17\u0e23\u0e07\u0e40\u0e1b\u0e34\u0e14 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e13 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e40\u0e02\u0e15\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 13 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2565<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/770\/\" rel=\"attachment wp-att-4090\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4090\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/770-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/771-2\/\" rel=\"attachment wp-att-4091\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4091\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/771-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/772\/\" rel=\"attachment wp-att-4092\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4092\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/772-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/773\/\" rel=\"attachment wp-att-4093\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4093\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/773-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/774\/\" rel=\"attachment wp-att-4094\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4094\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/774-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/775\/\" rel=\"attachment wp-att-4095\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4095\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/775-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/776\/\" rel=\"attachment wp-att-4096\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4096\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/776-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/777\/\" rel=\"attachment wp-att-4097\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4097\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/777-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/779\/\" rel=\"attachment wp-att-4098\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4098\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779.webp\" alt=\"\" width=\"1535\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779.webp 1535w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-1024x683.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-1170x781.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/779-263x175.webp 263w\" sizes=\"(max-width: 1535px) 100vw, 1535px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/778\/\" rel=\"attachment wp-att-4099\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4099\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778.webp\" alt=\"\" width=\"1535\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778.webp 1535w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-1024x683.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-1170x781.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/778-263x175.webp 263w\" sizes=\"(max-width: 1535px) 100vw, 1535px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/780\/\" rel=\"attachment wp-att-4100\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4100\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/780-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/781\/\" rel=\"attachment wp-att-4101\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4101\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/781-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/782\/\" rel=\"attachment wp-att-4102\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4102\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/782-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/783\/\" rel=\"attachment wp-att-4103\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4103\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/783-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/10\/13\/%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b8%a5%e0%b8%a7%e0%b8%87-%e0%b8%97%e0%b8%a3%e0%b8%87%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%a3%e0%b8%b2%e0%b8%8a\/attachment\/784\/\" rel=\"attachment wp-att-4104\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4104\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784.webp\" alt=\"\" width=\"1537\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784.webp 1537w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-300x200.webp 300w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-1024x682.webp 1024w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-768x512.webp 768w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-1170x779.webp 1170w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-585x390.webp 585w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/10\/784-263x175.webp 263w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u0e43\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e23\u0e07\u0e40\u0e1b&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-4089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-36"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4089"}],"version-history":[{"count":2,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4089\/revisions"}],"predecessor-version":[{"id":4106,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4089\/revisions\/4106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4096"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}