{"id":4326,"date":"2022-11-17T20:23:54","date_gmt":"2022-11-17T13:23:54","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4326"},"modified":"2022-12-13T11:30:46","modified_gmt":"2022-12-13T04:30:46","slug":"%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%a7%e0%b9%88%e0%b8%b2-%e0%b8%81%e0%b8%81%e0%b8%97-%e0%b8%82%e0%b8%ad%e0%b8%9a%e0%b8%84%e0%b8%b8%e0%b8%93-%e0%b8%9e%e0%b8%a5-%e0%b8%ad-%e0%b8%9b%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/11\/17\/%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%a7%e0%b9%88%e0%b8%b2-%e0%b8%81%e0%b8%81%e0%b8%97-%e0%b8%82%e0%b8%ad%e0%b8%9a%e0%b8%84%e0%b8%b8%e0%b8%93-%e0%b8%9e%e0%b8%a5-%e0%b8%ad-%e0%b8%9b%e0%b8%a3\/","title":{"rendered":"\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e01\u0e17. \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e44\u0e17\u0e22\u0e1b\u0e34\u0e14\u0e14\u0e35\u0e25 \u0e44\u0e14\u0e49\u0e14\u0e39\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01"},"content":{"rendered":"<p><span style=\"font-size: 20px; color: #993300;\"><strong>\u21d2 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e01\u0e17. \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e44\u0e17\u0e22\u0e1b\u0e34\u0e14\u0e14\u0e35\u0e25 \u0e44\u0e14\u0e49\u0e14\u0e39\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #993300;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span> : 17 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2565 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e01\u0e17. \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 \u201c\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23\u201d \u0e2b\u0e19\u0e38\u0e19\u0e44\u0e17\u0e22\u0e1b\u0e34\u0e14\u0e14\u0e35\u0e25 \u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e14\u0e39\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01 64 \u0e41\u0e21\u0e15\u0e0a\u0e4c \u0e0a\u0e31\u0e27\u0e23\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e04\u0e27\u0e32\u0e21\u0e04\u0e37\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01 2022 \u0e23\u0e2d\u0e1a\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e32\u0e15\u0e32\u0e23\u0e4c \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19-18 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e01\u0e2a\u0e17\u0e0a.) \u0e21\u0e35\u0e21\u0e15\u0e34\u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e17\u0e1b\u0e2a.) \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e01\u0e01\u0e17.) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01 2022 \u0e43\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 600 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e08\u0e32\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e15\u0e47\u0e21 \u0e17\u0e35\u0e48 \u0e01\u0e01\u0e17. \u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e44\u0e1b 1,600 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e17\u0e33\u0e43\u0e2b\u0e49 \u0e01\u0e01\u0e17. \u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e35\u0e01 1,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e43\u0e08\u0e14\u0e35 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e23\u0e39 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e4d\u0e32\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19), \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e4d\u0e32\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e15\u0e17. \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e27 400 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e19\u0e31\u0e49\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 17 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 <strong>\u0e14\u0e23.\u0e01\u0e49\u0e2d\u0e07\u0e28\u0e31\u0e01\u0e14 \u0e22\u0e2d\u0e14\u0e21\u0e13\u0e35<\/strong> \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e01\u0e01\u0e17.) \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e01\u0e01\u0e17. \u0e44\u0e14\u0e49\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e42\u0e25\u0e01 2022 \u0e01\u0e31\u0e1a\u0e2a\u0e2b\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 (\u0e1f\u0e35\u0e1f\u0e48\u0e32) \u0e08\u0e33\u0e19\u0e27\u0e19 64 \u0e41\u0e21\u0e15\u0e0a\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e19\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 33 \u0e25\u0e49\u0e32\u0e19\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e2a\u0e2b\u0e23\u0e31\u0e10 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,400 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e27\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e08\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e1b\u0e31\u0e17\u0e21\u0e32 \u0e25\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 \u0e44\u0e2d\u0e42\u0e2d\u0e0b\u0e35\u0e40\u0e21\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22, \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e25\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e20\u0e32\u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 (\u0e42\u0e2d\u0e0b\u0e35\u0e40\u0e2d) \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e04\u0e23\u0e1a 64 \u0e41\u0e21\u0e15\u0e0a\u0e4c \u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e31\u0e1a\u0e1f\u0e35\u0e1f\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e41\u0e21\u0e49\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e23\u0e32\u0e27\u0e46 1,180 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e35\u0e01 15% \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e08\u0e1a\u0e17\u0e35\u0e48 1,400 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/span><\/p>\n<p><span style=\"color: #993300;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/11\/04\/%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b8%98-%e0%b8%ad%e0%b8%ad%e0%b8%a1%e0%b8%aa%e0%b8%b4%e0%b8%99-%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/attachment\/960\/\" rel=\"attachment wp-att-4254\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4254\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e01\u0e17. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-4326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4326"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4326\/revisions"}],"predecessor-version":[{"id":4328,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4326\/revisions\/4328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4327"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}