{"id":4416,"date":"2022-11-06T00:48:59","date_gmt":"2022-11-05T17:48:59","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4416"},"modified":"2022-12-13T09:19:06","modified_gmt":"2022-12-13T02:19:06","slug":"%e0%b9%81%e0%b8%84%e0%b8%a1%e0%b9%80%e0%b8%9b%e0%b8%8d-friend-of-sacit-%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2%e0%b9%80%e0%b8%9e%e0%b8%b4","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2022\/11\/06\/%e0%b9%81%e0%b8%84%e0%b8%a1%e0%b9%80%e0%b8%9b%e0%b8%8d-friend-of-sacit-%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2%e0%b9%80%e0%b8%9e%e0%b8%b4\/","title":{"rendered":"\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Friend of sacit \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u0e42\u0e01\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c"},"content":{"rendered":"<p><span style=\"font-size: 20px; color: #993300;\"><strong>\u21d2 \u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Friend of sacit \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u0e42\u0e01\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #993300;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span>\u00a0: 6 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2565 \u0e19\u0e32\u0e22\u0e01\u0e2f \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Friend of sacit \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19 Gen Z \u0e43\u0e2a\u0e48\u0e0a\u0e38\u0e14\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e14\u0e32\u0e23\u0e32 \u0e04\u0e19\u0e14\u0e31\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e42\u0e01\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e44\u0e15\u0e23\u0e2a\u0e23\u0e13\u0e01\u0e38\u0e25<\/strong> \u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30 \u0e23\u0e21\u0e27.\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Friend of sacit \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e34\u0e25\u0e1b\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e2d\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e44\u0e14\u0e49\u0e0a\u0e27\u0e19\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201c\u0e41\u0e1b\u0e25\u0e07\u0e42\u0e09\u0e21\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19 Gen Z \u0e14\u0e49\u0e27\u0e22\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\u201d \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19\u0e21\u0e32\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e0a\u0e38\u0e14\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e01\u0e32\u0e23\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\u0e43\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e40\u0e1b\u0e47\u0e19 Soft Power \u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e1a\u0e27\u0e01\u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Friend of sacit \u0e44\u0e14\u0e49\u0e40\u0e0a\u0e34\u0e0d\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e14\u0e32\u0e23\u0e32 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e40\u0e0b\u0e40\u0e25\u0e1a\u0e23\u0e34\u0e15\u0e35\u0e49\u0e04\u0e19\u0e14\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e41\u0e27\u0e14\u0e27\u0e07\u0e07\u0e32\u0e19\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e44\u0e17\u0e22\u0e43\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e01\u0e25\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e17\u0e22\u0e21\u0e35\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e32\u0e19\u0e17\u0e38\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19 Soft Power \u0e44\u0e17\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e17\u0e38\u0e19\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e20\u0e39\u0e21\u0e34 \u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e43\u0e19\u0e40\u0e27\u0e17\u0e35\u0e42\u0e25\u0e01<\/span><\/p>\n<p><span style=\"color: #993300;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2022\/11\/04\/%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b8%98-%e0%b8%ad%e0%b8%ad%e0%b8%a1%e0%b8%aa%e0%b8%b4%e0%b8%99-%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/attachment\/960\/\" rel=\"attachment wp-att-4254\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4254\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/11\/960-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Frien&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-4416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4416"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4416\/revisions"}],"predecessor-version":[{"id":4418,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4416\/revisions\/4418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4417"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}