{"id":4597,"date":"2023-01-15T08:33:42","date_gmt":"2023-01-15T01:33:42","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4597"},"modified":"2023-02-01T13:15:18","modified_gmt":"2023-02-01T06:15:18","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%9a%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%aa%e0%b8%b3%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%88-e-service","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/01\/15\/%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%9a%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%aa%e0%b8%b3%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%88-e-service\/","title":{"rendered":"\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 e-Service \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e16\u0e36\u0e07 725 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23"},"content":{"rendered":"<p><span style=\"color: #993300; font-size: 20px;\"><strong>\u21d2 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 e-Service \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e16\u0e36\u0e07 725 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #993300;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span> : 15 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2566 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 e-Service \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01.\u0e1e.\u0e23. \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 725 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e07\u0e32\u0e19 3 \u0e14\u0e49\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\/\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35 \u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e08\u0e1a\u0e43\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e44\u0e15\u0e23\u0e2a\u0e23\u0e13\u0e01\u0e38\u0e25<\/strong> \u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e14\u0e49\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e1c\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30 \u0e23\u0e21\u0e27.\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d e-Service \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e25\u0e14\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 (\u0e01.\u0e1e.\u0e23.) \u0e44\u0e14\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 e-Service \u0e17\u0e35\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e23\u0e27\u0e21 725 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 3 \u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01.\u0e1e.\u0e23. \u0e17\u0e35\u0e48\u0e25\u0e34\u0e07\u0e04\u0e4c http:\/\/bit.ly\/3veQn5L \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e41\u0e01\u0e19\u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 e-Service \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e17\u0e31\u0e49\u0e07 725 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 3 \u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 1 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e23\u0e27\u0e21 82 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e48\u0e2d\u0e22\u0e2d\u0e35\u0e01 8 \u0e14\u0e49\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1)\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d 10 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 13 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 3)\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 10 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 4)\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c 11 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 5)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 15 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 6)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 4 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 7)\u0e14\u0e49\u0e32\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 16 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 8)\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e 3 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 2 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e21\u0e35\u0e07\u0e32\u0e19\u0e17\u0e33\u0e23\u0e27\u0e21 98 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e48\u0e2d\u0e22 4 \u0e14\u0e49\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 12 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2) \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 15 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 3) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e 39 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 4)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 32 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19.\u0e2a.\u0e44\u0e15\u0e23\u0e28\u0e38\u0e25\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 3 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\/SMEs \u0e23\u0e27\u0e21 545 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e48\u0e2d\u0e22 6 \u0e14\u0e49\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e41\u0e25\u0e30\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 248 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 68 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 3)\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 9 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 4)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c 82 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 5)\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01-\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 86 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 6)\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 52 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"color: #993300;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/600x800-16\/\" rel=\"attachment wp-att-4431\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4431\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/12\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/12\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/12\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2022\/12\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-4597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4597"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4597\/revisions"}],"predecessor-version":[{"id":4599,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4597\/revisions\/4599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4598"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}