{"id":4719,"date":"2023-02-03T13:45:04","date_gmt":"2023-02-03T06:45:04","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4719"},"modified":"2023-03-03T00:34:16","modified_gmt":"2023-03-02T17:34:16","slug":"%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%81%e0%b8%b3%e0%b8%8a%e0%b8%b1%e0%b8%9a-%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%88%e0%b8%b1%e0%b8%87%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%9a%e0%b9%88","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/02\/03\/%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%81%e0%b8%b3%e0%b8%8a%e0%b8%b1%e0%b8%9a-%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%88%e0%b8%b1%e0%b8%87%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%9a%e0%b9%88\/","title":{"rendered":"\u0e01\u0e01\u0e15.\u0e01\u0e33\u0e0a\u0e31\u0e1a \u0e01\u0e01\u0e15.\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e2a.\u0e2a. \u0e22\u0e36\u0e14 \u0e01\u0e21.-\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19"},"content":{"rendered":"<p><span style=\"font-size: 28px; color: #0000ff;\"><strong>\u21d2 \u0e01\u0e01\u0e15.\u0e01\u0e33\u0e0a\u0e31\u0e1a \u0e01\u0e01\u0e15.\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e2a.\u0e2a. \u0e22\u0e36\u0e14 \u0e01\u0e21.-\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #0000ff;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong> <\/span>: 3 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u0e01\u0e33\u0e0a\u0e31\u0e1a \u0e01\u0e01\u0e15.\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e2a.\u0e2a. \u0e22\u0e36\u0e14\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e2a.\u0e2a.\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u00a0 \u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07 \u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 \u0e1e.\u0e28. 2566 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a.\u0e41\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e2a.\u0e2a.\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e01\u0e15. \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a.\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 1 \u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 3 \u0e27\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e1a\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15 \u0e43\u0e2b\u0e49\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 3 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 10 \u0e27\u0e31\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e0b\u0e36\u0e48\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e33\u0e1a\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u00a0 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e15\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 1 \u0e04\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e1c\u0e25\u0e15\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e40\u0e01\u0e34\u0e19\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 10 \u0e02\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e15\u0e48\u0e2d\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e38\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 1 \u0e04\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e13\u0e35\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/02\/03\/%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%81%e0%b8%b3%e0%b8%8a%e0%b8%b1%e0%b8%9a-%e0%b8%81%e0%b8%81%e0%b8%95-%e0%b8%88%e0%b8%b1%e0%b8%87%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%9a%e0%b9%88\/attachment\/339\/\" rel=\"attachment wp-att-4720\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4720\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/339.webp\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/339.webp 576w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/339-169x300.webp 169w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><span style=\"font-size: 16px;\">\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e14\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a.\u0e41\u0e1a\u0e1a\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15 \u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a.\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2562 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e15\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e31\u0e49\u0e19\u00a0 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1c\u0e25\u0e15\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u00a0 \u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2562\u00a0 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e28\u0e32\u0e25\u0e32\u0e01\u0e25\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e33\u0e1a\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e28\u0e32\u0e25\u0e32\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15 \u0e41\u0e25\u0e30\u0e28\u0e32\u0e25\u0e32\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e01\u0e15.\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e2a.\u0e2a.\u0e41\u0e1a\u0e1a\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 1 \u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e02\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e01\u0e15.\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e28\u0e32\u0e25\u0e32\u0e01\u0e25\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e33\u0e1a\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e01\u0e15. \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/attachment\/729489\/\" rel=\"attachment wp-att-4704\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4704\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2 \u0e01\u0e01\u0e15.\u0e01\u0e33\u0e0a\u0e31\u0e1a \u0e01\u0e01&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,42],"tags":[],"class_list":["post-4719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-42"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4719"}],"version-history":[{"count":2,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4719\/revisions"}],"predecessor-version":[{"id":4722,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4719\/revisions\/4722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4678"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}