{"id":4909,"date":"2023-02-28T20:20:51","date_gmt":"2023-02-28T13:20:51","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=4909"},"modified":"2023-03-03T01:48:50","modified_gmt":"2023-03-02T18:48:50","slug":"%e0%b8%a3%e0%b8%a1%e0%b8%8a-%e0%b8%aa%e0%b8%b1%e0%b8%99%e0%b8%95%e0%b8%b4-%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%84%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%a1%e0%b8%b5%e0%b8%87%e0%b8%9a","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/02\/28\/%e0%b8%a3%e0%b8%a1%e0%b8%8a-%e0%b8%aa%e0%b8%b1%e0%b8%99%e0%b8%95%e0%b8%b4-%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%84%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%a1%e0%b8%b5%e0%b8%87%e0%b8%9a\/","title":{"rendered":"\u201c\u0e23\u0e21\u0e0a.\u0e2a\u0e31\u0e19\u0e15\u0e34\u201d \u0e22\u0e31\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e21\u0e35\u0e07\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 \u201c\u0e1a\u0e31\u0e15\u0e23\u0e04\u0e19\u0e08\u0e19\u201d \u0e23\u0e2d\u0e1a\u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"<p><span style=\"font-size: 28px; color: #333399;\">\u21d2\u201c\u0e23\u0e21\u0e0a.\u0e2a\u0e31\u0e19\u0e15\u0e34\u201d \u0e22\u0e31\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e21\u0e35\u0e07\u0e1a\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 \u201c\u0e1a\u0e31\u0e15\u0e23\u0e04\u0e19\u0e08\u0e19\u201d \u0e23\u0e2d\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #333399;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/strong>\u00a0: 28 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u2018\u0e2a\u0e31\u0e19\u0e15\u0e34\u2019 \u0e22\u0e31\u0e19\u0e04\u0e25\u0e31\u0e07\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1e\u0e2d \u0e2b\u0e25\u0e31\u0e07 \u0e04\u0e23\u0e21.\u0e44\u0e1f\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e27\u0e07\u0e40\u0e07\u0e34\u0e19 \u201c\u0e1a\u0e31\u0e15\u0e23\u0e04\u0e19\u0e08\u0e19\u201d \u0e23\u0e2d\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e25\u0e31\u0e48\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u201c\u0e1b\u0e49\u0e2d\u0e21 700\u201d \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e08\u0e48\u0e32\u0e22 100% \u0e1b\u0e31\u0e14\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c \u201c\u0e15\u0e39\u0e48 1,000\u201d \u0e40\u0e1c\u0e22\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e4c<\/strong> \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e23\u0e13\u0e35 \u0e04\u0e23\u0e21.\u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e15\u0e23\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e23\u0e31\u0e10\u0e23\u0e2d\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e27\u0e48\u0e32 \u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07 1 \u0e41\u0e2a\u0e19\u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e1b\u0e35\u0e40\u0e1b\u0e47\u0e19 300 \u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49 200-300 \u0e1a\u0e32\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e21\u0e35\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e15\u0e23\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e23\u0e31\u0e10<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e23\u0e23\u0e04\u0e23\u0e27\u0e21\u0e44\u0e17\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e44\u0e14\u0e49\u0e0a\u0e39\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e2a\u0e40\u0e1b\u0e47\u0e19 1,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e08\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e21\u0e32\u0e04\u0e33\u0e19\u0e27\u0e19 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e04\u0e33\u0e19\u0e27\u0e19\u0e14\u0e39\u0e27\u0e48\u0e32 14.5 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e17\u0e18\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e08\u0e30\u0e21\u0e35\u0e01\u0e27\u0e48\u0e32 16-17 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e1b\u0e35\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e41\u0e2a\u0e19\u0e01\u0e27\u0e48\u0e32\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10\u0e1a\u0e31\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 700 \u0e1a\u0e32\u0e17\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e19\u0e31\u0e48\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e27\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e17\u0e33\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e1e\u0e23\u0e23\u0e04\u0e2d\u0e2d\u0e01\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e01\u0e17\u0e31\u0e1a\u0e01\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e23\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08 \u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e2b\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e04\u0e23\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e04\u0e34\u0e14\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e47\u0e04\u0e34\u0e14 \u0e2b\u0e32\u0e01\u0e08\u0e30\u0e04\u0e34\u0e14\u0e21\u0e32\u0e01\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32\u0e40\u0e07\u0e34\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e25\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e40\u0e22\u0e2d\u0e30\u0e46 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1e\u0e23\u0e23\u0e04 \u0e2a\u0e48\u0e27\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e01\u0e47\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 100% \u0e27\u0e48\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10\u0e21\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e25\u0e31\u0e48\u0e19\u0e01\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e1c\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e01\u0e47\u0e2b\u0e32\u0e40\u0e07\u0e34\u0e19\u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u201d \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e23\u0e04 \u0e1e\u0e1b\u0e0a\u0e23. \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32 \u0e17\u0e38\u0e01\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e35\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e15\u0e19\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e40\u0e07\u0e34\u0e19\u0e21\u0e32\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e43\u0e19 \u0e04\u0e23\u0e21.\u0e27\u0e48\u0e32\u0e08\u0e30\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e49\u0e32\u0e22\u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e15\u0e19\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e08\u0e30\u0e44\u0e14\u0e49\u0e22\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/attachment\/729489\/\" rel=\"attachment wp-att-4704\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4704\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/02\/729489-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2\u201c\u0e23\u0e21\u0e0a.\u0e2a\u0e31\u0e19\u0e15\u0e34\u201d \u0e22&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,40],"tags":[],"class_list":["post-4909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-40"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=4909"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4909\/revisions"}],"predecessor-version":[{"id":4911,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/4909\/revisions\/4911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/4910"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=4909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=4909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=4909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}