{"id":5070,"date":"2023-03-28T23:30:18","date_gmt":"2023-03-28T16:30:18","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=5070"},"modified":"2023-04-05T10:58:00","modified_gmt":"2023-04-05T03:58:00","slug":"%e0%b8%a8%e0%b8%b2%e0%b8%a5%e0%b8%9b%e0%b8%81%e0%b8%84%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%b9%e0%b8%87%e0%b8%aa%e0%b8%b8%e0%b8%94%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/03\/28\/%e0%b8%a8%e0%b8%b2%e0%b8%a5%e0%b8%9b%e0%b8%81%e0%b8%84%e0%b8%a3%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%b9%e0%b8%87%e0%b8%aa%e0%b8%b8%e0%b8%94%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%84\/","title":{"rendered":"\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e21\u0e35\u0e21\u0e15\u0e34\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 \u201d\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e44\u0e01\u0e23\u201d \u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u00a0 \u0e1e.\u0e23.\u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32 66"},"content":{"rendered":"<p><span style=\"font-size: 28px; color: #333399;\">\u21d2\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e21\u0e35\u0e21\u0e15\u0e34\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 \u201d\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e44\u0e01\u0e23\u201d \u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u00a0 \u0e1e.\u0e23.\u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32 66<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span> : 28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2566\u00a0\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e01\u0e23\u0e13\u0e35\u0e19\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e44\u0e01\u0e23 \u0e25\u0e35\u0e01\u0e34\u0e08\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 \u0e22\u0e37\u0e48\u0e19\u0e1f\u0e49\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e01\u0e23\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15\u0e43\u0e0a\u0e49\u0e14\u0e38\u0e25\u0e1e\u0e34\u0e19\u0e34\u0e08\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e21\u0e32\u0e15\u0e23\u0e32 103 \u0e27\u0e23\u0e23\u0e04\u0e2a\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e28\u0e32\u0e25\u0e2f\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49 \u0e1e.\u0e23 \u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 2566 \u0e21\u0e35\u0e1c\u0e25\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19 \u0e1e.\u0e23.\u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 2566 \u0e17\u0e35\u0e48\u0e15\u0e23\u0e32\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e21\u0e32\u0e15\u0e23\u0e32 103 \u0e27\u0e23\u0e23\u0e04\u0e2a\u0e2d\u0e07 \u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e08\u0e30\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32 \u0e41\u0e15\u0e48\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e23\u0e32\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e44\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e15\u0e23\u0e32\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e32\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e44\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e27\u0e07\u0e14\u0e38\u0e25\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1d\u0e48\u0e32\u0e22\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e15\u0e32\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32\u0e15\u0e32\u0e21\u0e19\u0e31\u0e22\u0e21\u0e32\u0e15\u0e23\u0e32 11(2) \u0e41\u0e2b\u0e48\u0e07 \u0e1e.\u0e23.\u0e1a.\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 2542 \u0e04\u0e14\u0e35\u0e1e\u0e34\u0e1e\u0e32\u0e17\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e1e.\u0e23.\u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 2566 \u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32\u0e04\u0e14\u0e35 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e14\u0e49\u0e40\u0e04\u0e22\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e44\u0e27\u0e49\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e14\u0e35 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e14\u0e35\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e14\u0e33\u0e17\u0e35\u0e48 \u0e1f.5\/2549 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e41\u0e14\u0e07\u0e17\u0e35\u0e48 \u0e1f. 3\/2549 \u0e04\u0e14\u0e35\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e14\u0e33\u0e17\u0e35\u0e48 \u0e1f. 100\/2556 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e41\u0e14\u0e07\u0e17\u0e35\u0e48 \u0e1f.12 7\/2556<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e19\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e44\u0e01\u0e23\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e43\u0e19\u0e21\u0e32\u0e15\u0e23\u0e32 102 \u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e32 197 \u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e32 9 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e32 72 \u0e02\u0e2d\u0e07 \u0e1e.\u0e23.\u0e1a.\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e04\u0e14\u0e35\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 2542 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e02\u0e2d \u0e08\u0e36\u0e07\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e44\u0e27\u0e49\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e14\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e23\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e04\u0e33\u0e02\u0e2d\u0e44\u0e15\u0e48\u0e2a\u0e27\u0e19\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e13\u0e35\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e08\u0e33\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e33\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e28\u0e32\u0e25\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e07\u0e31\u0e1a \u0e1e.\u0e23 \u0e0e.\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 2566 \u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e25\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e21\u0e35\u0e04\u0e33\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/03\/01\/%e0%b9%80%e0%b8%a8%e0%b8%a3%e0%b8%a9%e0%b8%90%e0%b8%b2-%e0%b9%80%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%9e%e0%b8%a3%e0%b8%a3%e0%b8%84%e0%b9%80%e0%b8%9e%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b9%84\/attachment\/525\/\" rel=\"attachment wp-att-4922\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4922\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/03\/525.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/03\/525.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/03\/525-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/03\/525-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2\u0e28\u0e32\u0e25\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e2a&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[43,37],"tags":[],"class_list":["post-5070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-43","category-37"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=5070"}],"version-history":[{"count":2,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5070\/revisions"}],"predecessor-version":[{"id":5073,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5070\/revisions\/5073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/5071"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=5070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=5070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=5070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}