{"id":5383,"date":"2023-05-16T14:01:25","date_gmt":"2023-05-16T07:01:25","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=5383"},"modified":"2023-06-04T15:29:33","modified_gmt":"2023-06-04T08:29:33","slug":"%e0%b9%80%e0%b8%a8%e0%b8%a3%e0%b8%a9%e0%b8%90%e0%b8%b2-%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%81%e0%b8%9e%e0%b8%a3%e0%b8%a3%e0%b8%84%e0%b9%82%e0%b8%8a%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/05\/16\/%e0%b9%80%e0%b8%a8%e0%b8%a3%e0%b8%a9%e0%b8%90%e0%b8%b2-%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%81%e0%b8%9e%e0%b8%a3%e0%b8%a3%e0%b8%84%e0%b9%82%e0%b8%8a%e0%b8%a7\/","title":{"rendered":"\u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u201d \u0e2b\u0e27\u0e31\u0e07\u0e17\u0e38\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e42\u0e0a\u0e27\u0e4c\u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e42\u0e2b\u0e27\u0e15\u0e2b\u0e19\u0e38\u0e19 \u201c\u0e1e\u0e34\u0e18\u0e32\u201d \u0e19\u0e31\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2f"},"content":{"rendered":"<p><span style=\"font-size: 28px; color: #333399;\">\u21d2\u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u201d \u0e2b\u0e27\u0e31\u0e07\u0e17\u0e38\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e42\u0e0a\u0e27\u0e4c\u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e42\u0e2b\u0e27\u0e15\u0e2b\u0e19\u0e38\u0e19 \u201c\u0e1e\u0e34\u0e18\u0e32\u201d \u0e19\u0e31\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2f<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #333399;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/strong>\u00a0: 16 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2566 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u201d \u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e42\u0e0a\u0e27\u0e4c\u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e42\u0e2b\u0e27\u0e15\u0e2b\u0e19\u0e38\u0e19 \u201c\u0e1e\u0e34\u0e18\u0e32\u201d \u0e19\u0e31\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21 \u0e40\u0e15\u0e47\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d 250 \u0e2a.\u0e27. \u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19<\/strong> \u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u201c\u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e38\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e22\u0e36\u0e14\u0e42\u0e22\u0e07\u0e41\u0e25\u0e30\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e17\u0e35\u0e48\u0e43\u0e19\u0e40\u0e23\u0e47\u0e27\u0e46 \u0e19\u0e35\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e25\u0e30\u0e42\u0e2b\u0e27\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e1c\u0e21\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e1e\u0e34\u0e18\u0e32 \u0e08\u0e32\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e42\u0e15\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01 81 \u0e04\u0e19 \u0e43\u0e19\u0e1b\u0e35 62 \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19 152 \u0e43\u0e19\u0e1b\u0e35 66 (\u0e40\u0e25\u0e02\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14) \u0e40\u0e25\u0e02\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e2a.\u0e2a. \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e44\u0e14\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e27\u0e48\u0e32 \u0e2d\u0e38\u0e14\u0e21\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e09\u0e31\u0e19\u0e17\u0e32\u0e21\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e23\u0e04\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49 \u0e2a.\u0e2a. \u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e35\u0e49 \u0e2b\u0e25\u0e32\u0e22\u0e1e\u0e23\u0e23\u0e04 (\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e31\u0e15\u0e22\u0e4c) \u0e40\u0e04\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e08\u0e38\u0e14\u0e22\u0e37\u0e19\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e23\u0e18\u0e19. \u0e1b\u0e35 60 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e2a.\u0e27. \u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e2b\u0e27\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e32\u0e22\u0e01\u0e2f<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e17\u0e48\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e15\u0e32\u0e21\u0e08\u0e38\u0e14\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e17\u0e48\u0e32\u0e19 \u0e42\u0e2b\u0e27\u0e15\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e40\u0e2a\u0e19\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e1e\u0e34\u0e18\u0e32 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e04\u0e19\u0e17\u0e35\u0e48 30 \u0e15\u0e32\u0e21\u0e01\u0e15\u0e34\u0e01\u0e32\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49 \u0e2a.\u0e27. 250 \u0e04\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34 \u0e1e\u0e39\u0e14\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e1b\u0e32\u0e01\u0e27\u0e48\u0e32 Represent \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e15\u0e31\u0e27 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e30\u0e19\u0e33\u0e1e\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e23\u0e04\u0e17\u0e33 \u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e01\u0e40\u0e09\u0e22\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e41\u0e1e\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e04\u0e23\u0e31\u0e1a\u201d<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e41\u0e2b\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e19\u0e48\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e27\u0e41\u0e19\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u0e40\u0e2d\u0e07<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/05\/03\/%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%98%e0%b8%b2%e0%b8%a3-%e0%b8%9a%e0%b8%ad%e0%b8%81-%e0%b8%97%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b4%e0%b8%93\/attachment\/760\/\" rel=\"attachment wp-att-5296\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-5296\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/05\/760.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/05\/760.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/05\/760-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/05\/760-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u21d2\u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u201d \u0e2b\u0e27\u0e31\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,40],"tags":[],"class_list":["post-5383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-40"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=5383"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5383\/revisions"}],"predecessor-version":[{"id":5385,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5383\/revisions\/5385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/5384"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=5383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=5383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=5383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}