{"id":5695,"date":"2023-07-06T18:22:42","date_gmt":"2023-07-06T11:22:42","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=5695"},"modified":"2023-08-28T10:14:56","modified_gmt":"2023-08-28T03:14:56","slug":"%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%8a%e0%b8%a9%e0%b8%90%e0%b9%8c-%e0%b9%81%e0%b8%a2%e0%b9%89%e0%b8%a1-%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%a3%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%a5","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/07\/06\/%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%8a%e0%b8%a9%e0%b8%90%e0%b9%8c-%e0%b9%81%e0%b8%a2%e0%b9%89%e0%b8%a1-%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%a3%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%a5\/","title":{"rendered":"\u201c\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c\u201d \u0e41\u0e22\u0e49\u0e21 \u0e27\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e32\u0e22\u0e01\u0e2f 3 \u0e04\u0e23\u0e31\u0e49\u0e07"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #333399;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/strong>\u00a0: 6 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e32\u0e19 \u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e04\u0e19\u0e17\u0e35\u0e48 2\u00a0 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e44\u0e14\u0e49\u0e27\u0e32\u0e07\u0e27\u0e31\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e44\u0e27\u0e49 13 \u0e01.\u0e04. \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e47\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e2d\u0e1a\u0e17\u0e35\u0e48 2 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e01.\u0e04.\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e1a\u0e17\u0e35\u0e48 3 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e01.\u0e04. \u0e04\u0e32\u0e14 3 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e44\u0e14\u0e49\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e49\u0e27 \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e47\u0e08\u0e30\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49 3 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1a\u0e48\u0e2d\u0e22\u0e46\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 750 \u0e04\u0e19 \u0e01\u0e47\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e25\u0e33\u0e1a\u0e32\u0e01 \u0e40\u0e27\u0e25\u0e32 3 \u0e27\u0e31\u0e19\u0e01\u0e47\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19 3 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e23\u0e13\u0e35\u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 3 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 8 \u0e1e\u0e23\u0e23\u0e04 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e15\u0e32\u0e21 MOU \u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e30\u0e44\u0e23 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e17\u0e23\u0e32\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e0a\u0e31\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e2b\u0e27\u0e15\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e22\u0e1e\u0e34\u0e18\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e41\u0e25\u0e30\u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e15\u0e48\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e2a.\u0e27. \u0e21\u0e35\u0e40\u0e08\u0e15\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e25\u0e38\u0e25\u0e48\u0e27\u0e07\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/07\/01\/%e0%b9%82%e0%b8%a0%e0%b8%84%e0%b8%b4%e0%b8%99-%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b8%ab%e0%b8%b2%e0%b8%81%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2\/462-3\/\" rel=\"attachment wp-att-5628\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-5628\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/462.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/462.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/462-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/462-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,39],"tags":[],"class_list":["post-5695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-39"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=5695"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5695\/revisions"}],"predecessor-version":[{"id":5697,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5695\/revisions\/5697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/5696"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=5695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=5695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=5695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}