{"id":5987,"date":"2023-07-02T15:24:06","date_gmt":"2023-07-02T08:24:06","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=5987"},"modified":"2023-08-28T10:06:48","modified_gmt":"2023-08-28T03:06:48","slug":"%e0%b8%9a%e0%b8%b4%e0%b9%8a%e0%b8%81%e0%b8%9b%e0%b9%89%e0%b8%ad%e0%b8%a1-%e0%b8%9b%e0%b8%b1%e0%b8%94%e0%b8%94%e0%b8%b5%e0%b8%a5-%e0%b8%9e%e0%b8%97-%e0%b8%99%e0%b8%b1%e0%b9%88","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/07\/02\/%e0%b8%9a%e0%b8%b4%e0%b9%8a%e0%b8%81%e0%b8%9b%e0%b9%89%e0%b8%ad%e0%b8%a1-%e0%b8%9b%e0%b8%b1%e0%b8%94%e0%b8%94%e0%b8%b5%e0%b8%a5-%e0%b8%9e%e0%b8%97-%e0%b8%99%e0%b8%b1%e0%b9%88\/","title":{"rendered":"\u201c\u0e1a\u0e34\u0e4a\u0e01\u0e1b\u0e49\u0e2d\u0e21\u201d \u0e1b\u0e31\u0e14\u0e14\u0e35\u0e25 \u0e1e\u0e17.\u0e19\u0e31\u0e48\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e25\u0e31\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07\u0e21\u0e32\u0e01\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #333399;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span> :<\/strong> 2 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 14.30 \u0e19. \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 2 \u0e01.\u0e04.66 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 <strong>\u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e27\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13<\/strong> \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e41\u0e25\u0e30\u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 \u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e2a.\u0e2a.\u0e43\u0e2b\u0e21\u0e48 \u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e42\u0e2b\u0e27\u0e15\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 \u0e27\u0e48\u0e32 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e16\u0e36\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e40\u0e25\u0e22 \u0e15\u0e49\u0e2d\u0e07\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01.\u0e04.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e16\u0e32\u0e21\u0e16\u0e36\u0e07\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e02\u0e48\u0e32\u0e27\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e27\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2d\u0e30\u0e44\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e08\u0e30\u0e44\u0e1b\u0e19\u0e31\u0e48\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e21\u0e35 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e22\u0e49\u0e33\u0e27\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e21\u0e35\u0e02\u0e48\u0e32\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e02\u0e48\u0e32\u0e27\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e16\u0e32\u0e21\u0e04\u0e19\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e02\u0e48\u0e32\u0e27 \u201c\u0e1c\u0e21\u0e1a\u0e2d\u0e01\u0e41\u0e25\u0e49\u0e27\u0e44\u0e07\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e21\u201d<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e02\u0e31\u0e49\u0e27\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e21\u0e22\u0e31\u0e07\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21\u0e43\u0e0a\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e43\u0e04\u0e23\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e01\u0e47\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e22\u0e49\u0e33\u0e27\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e22\u0e31\u0e07\u0e04\u0e07\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21\u0e43\u0e0a\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30 \u0e23\u0e21\u0e27.\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e23\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1e\u0e23\u0e23\u0e04\u0e23\u0e27\u0e21\u0e44\u0e17\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e1a\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e44\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e02\u0e48\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e15\u0e2d\u0e1a\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49 \u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e16\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e02\u0e31\u0e49\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e1e\u0e25.\u0e2d.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e15\u0e23 \u0e44\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/600x800280766\/\" rel=\"attachment wp-att-5762\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-5762\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,40],"tags":[],"class_list":["post-5987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-40"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=5987"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5987\/revisions"}],"predecessor-version":[{"id":5989,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/5987\/revisions\/5989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/5988"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=5987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=5987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=5987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}