{"id":6038,"date":"2023-08-13T22:01:15","date_gmt":"2023-08-13T15:01:15","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=6038"},"modified":"2023-08-31T12:36:58","modified_gmt":"2023-08-31T05:36:58","slug":"%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b2-%e0%b8%9b%e0%b8%a5%e0%b8%b8%e0%b8%81%e0%b8%84%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%a2%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%ab","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/08\/13\/%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b2-%e0%b8%9b%e0%b8%a5%e0%b8%b8%e0%b8%81%e0%b8%84%e0%b8%99%e0%b8%a3%e0%b8%b0%e0%b8%a2%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%ab\/","title":{"rendered":"\u201c\u0e1e\u0e34\u0e18\u0e32\u201d \u0e1b\u0e25\u0e38\u0e01\u0e04\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e2b\u0e21\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e02\u0e15 3 \u0e01\u0e32\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e43\u0e2b\u0e49\u0e16\u0e25\u0e48\u0e21\u0e17\u0e25\u0e32\u0e22"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span>\u00a0<strong>: <\/strong>13 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2566 \u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e18\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e0a\u0e31\u0e22\u0e18\u0e27\u0e31\u0e0a \u0e15\u0e38\u0e25\u0e32\u0e18\u0e19 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e23\u0e04 \u0e1b\u0e23\u0e32\u0e28\u0e23\u0e31\u0e22\u0e2b\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e32\u0e22\u0e1e\u0e07\u0e28\u0e18\u0e23 \u0e28\u0e23\u0e40\u0e1e\u0e0a\u0e23\u0e19\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e42\u0e22 \u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e2a\u0e2a. \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e40\u0e02\u0e15 3 \u0e17\u0e35\u0e48\u0e27\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e2d.\u0e40\u0e02\u0e32\u0e0a\u0e30\u0e40\u0e21\u0e32 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e25\u0e07\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e23\u0e2d\u0e1f\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e32\u0e28\u0e23\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e1e\u0e07\u0e28\u0e18\u0e23 \u0e1b\u0e23\u0e32\u0e28\u0e23\u0e31\u0e22\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e48\u0e2d\u0e15\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e41\u0e15\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19 \u0e15\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e36\u0e14\u0e2d\u0e31\u0e14\u0e04\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e2d\u0e36\u0e14\u0e2d\u0e31\u0e14\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e40\u0e25\u0e22 \u0e40\u0e2b\u0e47\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e14\u0e31\u0e07\u0e46 \u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e15\u0e19\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e0a\u0e30\u0e40\u0e21\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e44\u0e14\u0e49\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e04\u0e49\u0e32\u0e19\u0e42\u0e23\u0e07\u0e42\u0e21\u0e48\u0e2b\u0e34\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e25\u0e32\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e1a\u0e34\u0e14\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e27 \u0e08\u0e36\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e15\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2b\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e17\u0e23\u0e32\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e08\u0e36\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e49\u0e32\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e49\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e2d \u0e40\u0e23\u0e34\u0e48\u0e21\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e21\u0e35\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e01\u0e25\u0e31\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2d\u0e32\u0e08\u0e44\u0e1b\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e21\u0e15\u0e2d\u0e1a\u0e44\u0e1b\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e27\u0e48\u0e32 \u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e25\u0e49\u0e27\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e1d\u0e32\u0e01\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e40\u0e08\u0e15\u0e08\u0e33\u0e19\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u201d \u0e19\u0e32\u0e22\u0e1e\u0e07\u0e28\u0e18\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e32\u0e22\u0e1e\u0e34\u0e18\u0e32 \u0e02\u0e36\u0e49\u0e19\u0e1b\u0e23\u0e32\u0e28\u0e23\u0e31\u0e22\u0e27\u0e48\u0e32 \u0e04\u0e34\u0e14\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e40\u0e04\u0e22\u0e21\u0e35\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 \u0e40\u0e23\u0e32\u0e2b\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e27\u0e48\u0e32 \u2018\u0e21\u0e35\u0e25\u0e38\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e23\u0e32 \u0e21\u0e35\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35\u0e25\u0e38\u0e07\u2019 \u0e2a\u0e32\u0e21\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e01\u0e47\u0e1e\u0e39\u0e14\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e25\u0e38\u0e07\u0e44\u0e27\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e04\u0e19 \u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e30\u0e22\u0e2d\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e0a\u0e32\u0e27\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e21\u0e2b\u0e21\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e40\u0e14\u0e47\u0e14\u0e02\u0e32\u0e14 \u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e21\u0e32\u0e01 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e25\u0e48\u0e21\u0e17\u0e25\u0e32\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e07\u0e27\u0e25\u0e27\u0e48\u0e32 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e30\u0e44\u0e23\u0e19\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e08\u0e30\u0e2a\u0e39\u0e49\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e04\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e1e\u0e32\u0e42\u0e22 \u0e1e\u0e07\u0e28\u0e18\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e20\u0e32\u0e2f \u0e40\u0e2d\u0e32\u0e43\u0e2b\u0e49\u0e16\u0e25\u0e48\u0e21\u0e17\u0e25\u0e32\u0e22\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e40\u0e25\u0e22\u201d \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e22\u0e47\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 (13 \u0e2a.\u0e04.66) \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 16.00 \u0e19. \u0e1e\u0e23\u0e23\u0e04\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e21\u0e35\u0e40\u0e27\u0e17\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e2a\u0e2a. \u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e04\u0e25\u0e2d\u0e07\u0e16\u0e21\u0e41\u0e01\u0e25\u0e07 \u0e2d.\u0e41\u0e01\u0e25\u0e07 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/600x800280766\/\" rel=\"attachment wp-att-5762\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-5762\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/07\/600x800280766-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,40],"tags":[],"class_list":["post-6038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-40"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=6038"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6038\/revisions"}],"predecessor-version":[{"id":6040,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6038\/revisions\/6040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/6039"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=6038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=6038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=6038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}