{"id":6089,"date":"2023-09-02T10:18:13","date_gmt":"2023-09-02T03:18:13","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=6089"},"modified":"2023-10-02T00:16:50","modified_gmt":"2023-10-01T17:16:50","slug":"%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b8%94%e0%b9%80%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%af-%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/02\/%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b8%94%e0%b9%80%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%af-%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/","title":{"rendered":"\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07 \u0e04\u0e23\u0e21.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 1"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong>\u00a0<\/span><strong>: <\/strong>2 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566\u00a0\u0e23\u0e32\u0e0a\u0e01\u0e34\u0e08\u0e08\u0e32\u0e19\u0e38\u0e40\u0e1a\u0e01\u0e29\u0e32 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e21\u0e35\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e42\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e27\u0e48\u0e32 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e25\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e31\u0e01\u0e23\u0e32\u0e0a 2566 \u0e41\u0e25\u0e49\u0e27 \u0e19\u0e31\u0e49\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e2a\u0e37\u0e1a\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e43\u0e19\u0e21\u0e32\u0e15\u0e23\u0e32 158 \u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e41\u0e2b\u0e48\u0e07\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e44\u0e17\u0e22 \u0e08\u0e36\u0e07\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e27\u0e0a\u0e22\u0e0a\u0e31\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e40\u0e17\u0e1e\u0e2a\u0e38\u0e17\u0e34\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e1b\u0e32\u0e19\u0e1b\u0e23\u0e35\u0e22\u0e4c \u0e1e\u0e2b\u0e34\u0e17\u0e18\u0e32\u0e19\u0e38\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e0a\u0e32\u0e0d\u0e27\u0e35\u0e23\u0e01\u0e39\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e\u0e25.\u0e15.\u0e2d. \u0e1e\u0e31\u0e0a\u0e23\u0e27\u0e32\u0e17 \u0e27\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e1e\u0e35\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e2a\u0e32\u0e25\u0e35\u0e23\u0e31\u0e10\u0e27\u0e34\u0e20\u0e32\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e40\u0e1e\u0e47\u0e0a\u0e23 \u0e0a\u0e38\u0e19\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e17\u0e34\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e41\u0e2a\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e25\u0e32\u0e42\u0e2b\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e2d\u0e35\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e01\u0e24\u0e29\u0e0e\u0e32 \u0e08\u0e35\u0e19\u0e30\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e08\u0e38\u0e25\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2d\u0e21\u0e23\u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e08\u0e31\u0e01\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e41\u0e2a\u0e07\u0e21\u0e13\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e14\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e2b\u0e27\u0e31\u0e07\u0e28\u0e38\u0e20\u0e01\u0e34\u0e08\u0e42\u0e01\u0e28\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e35\u0e2c\u0e32<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e27\u0e23\u0e32\u0e27\u0e38\u0e18 \u0e28\u0e34\u0e25\u0e1b\u0e2d\u0e32\u0e0a\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e38\u0e20\u0e21\u0e32\u0e2a \u0e2d\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e01 \u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e1c\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e44\u0e0a\u0e22\u0e32 \u0e1e\u0e23\u0e2b\u0e21\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0a\u0e32 \u0e19\u0e32\u0e04\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 \u0e08\u0e36\u0e07\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e07\u0e21\u0e19\u0e1e\u0e23 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e28\u0e23\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e1b\u0e34\u0e22\u0e30\u0e42\u0e0a\u0e15\u0e34 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e23\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e19\u0e20\u0e34\u0e19\u0e17\u0e23 \u0e28\u0e23\u0e35\u0e2a\u0e23\u0e23\u0e1e\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e40\u0e01\u0e23\u0e35\u0e22\u0e07 \u0e01\u0e31\u0e25\u0e1b\u0e4c\u0e15\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e17\u0e23\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e17\u0e2d\u0e07\u0e28\u0e23\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e0a\u0e32\u0e14\u0e32 \u0e44\u0e17\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e.\u0e15.\u0e2d.\u0e17\u0e27\u0e35 \u0e2a\u0e2d\u0e14\u0e2a\u0e48\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e31\u0e0a\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1e\u0e07\u0e29\u0e4c\u0e1e\u0e32\u0e19\u0e34\u0e0a \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e\u0e25.\u0e15.\u0e2d.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e23\u0e01\u0e38\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e0a\u0e25\u0e19\u0e48\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e31\u0e17\u0e23\u0e32 \u0e27\u0e34\u0e0a\u0e31\u0e22\u0e01\u0e38\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/02\/%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b8%94%e0%b9%80%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%af-%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/914-2\/\" rel=\"attachment wp-att-6091\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6091\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/914.jpg\" alt=\"\" width=\"678\" height=\"960\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/914.jpg 678w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/914-212x300.jpg 212w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/914-585x828.jpg 585w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/02\/%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b8%94%e0%b9%80%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%af-%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/915-4\/\" rel=\"attachment wp-att-6092\"><img decoding=\"async\" class=\"alignnone size-full wp-image-6092\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/915.jpg\" alt=\"\" width=\"678\" height=\"960\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/915.jpg 678w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/915-212x300.jpg 212w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/915-585x828.jpg 585w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/02\/%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b8%94%e0%b9%80%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%af-%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%87\/attachment\/916\/\" rel=\"attachment wp-att-6093\"><img decoding=\"async\" class=\"alignnone size-full wp-image-6093\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/916.jpg\" alt=\"\" width=\"678\" height=\"960\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/916.jpg 678w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/916-212x300.jpg 212w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/916-585x828.jpg 585w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b8%94%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%9a%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%95%e0%b8%b4%e0%b8%94%e0%b8%aa%e0%b8%9b%e0%b8%b5%e0%b8%94\/september600x800\/\" rel=\"attachment wp-att-6064\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6064\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-6089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-36"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=6089"}],"version-history":[{"count":2,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6089\/revisions"}],"predecessor-version":[{"id":6096,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6089\/revisions\/6096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/6094"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=6089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=6089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=6089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}