{"id":6183,"date":"2023-09-13T21:00:19","date_gmt":"2023-09-13T14:00:19","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=6183"},"modified":"2023-10-02T00:35:11","modified_gmt":"2023-10-01T17:35:11","slug":"%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1-%e0%b8%84%e0%b8%a3%e0%b8%a1-%e0%b8%99%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%a3%e0%b8%81-%e0%b8%ad%e0%b8%99%e0%b8%b8","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/13\/%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1-%e0%b8%84%e0%b8%a3%e0%b8%a1-%e0%b8%99%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%a3%e0%b8%81-%e0%b8%ad%e0%b8%99%e0%b8%b8\/","title":{"rendered":"\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e04\u0e23\u0e21. \u0e19\u0e31\u0e14\u0e41\u0e23\u0e01 \u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34 10 \u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 Quick win \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e14\u0e36\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22\u0e1b\u0e35\u0e2b\u0e19\u0e49\u0e32 40 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span><strong>\u00a0:<\/strong> 13 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566\u00a0<strong>\u0e19\u0e32\u0e22\u0e0a\u0e31\u0e22 \u0e27\u0e31\u0e0a\u0e23\u0e07\u0e04\u0e4c<\/strong> \u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a 10 \u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23 Quick win \u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e25\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e42\u0e14\u0e22\u0e40\u0e23\u0e47\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e04\u0e32\u0e0b\u0e31\u0e04\u0e2a\u0e16\u0e32\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e48\u0e32 \u0e08\u0e35\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 200 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19\/\u0e1b\u0e35 \u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e30\u0e14\u0e36\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22\u0e43\u0e19\u0e1b\u0e35 2566 \u0e08\u0e33\u0e19\u0e27\u0e19 28 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e17\u0e33\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 1.4 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e43\u0e19\u0e1b\u0e35 2567 \u0e21\u0e35\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22 40 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e17\u0e22 180 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 3.1 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 1. \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e32\u0e0b\u0e31\u0e04\u0e2a\u0e16\u0e32\u0e19 2. \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22 3. \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e14\u0e36\u0e07\u0e14\u0e32\u0e23\u0e32 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08 \u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 4. \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e02\u0e38\u0e19\u0e1e\u0e25\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e42\u0e23\u0e14\u0e42\u0e0a\u0e27\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e17\u0e22 5. \u0e01\u0e32\u0e23\u0e14\u0e36\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e34\u0e19\u0e2b\u0e19\u0e34\u0e07 \u0e15\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e13\u0e11\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 6. \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 7. \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e08\u0e38\u0e14\u0e02\u0e32\u0e22 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49 365 \u0e27\u0e31\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e25\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e17\u0e07 \u0e15\u0e49\u0e2d\u0e07\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e04\u0e25\u0e32\u0e2a \u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 8. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e23\u0e32\u0e04\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1d\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 9. \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e17\u0e22 10. \u0e15\u0e31\u0e49\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e08\u0e49\u0e07\u0e02\u0e48\u0e32\u0e27 \u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e17\u0e32\u0e07\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e40\u0e2b\u0e15\u0e38 \u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e44\u0e14\u0e49\u0e43\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e17\u0e22<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b8%94%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%9a%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%95%e0%b8%b4%e0%b8%94%e0%b8%aa%e0%b8%9b%e0%b8%b5%e0%b8%94\/september600x800\/\" rel=\"attachment wp-att-6064\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6064\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-6183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=6183"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6183\/revisions"}],"predecessor-version":[{"id":6185,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6183\/revisions\/6185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/6184"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=6183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=6183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=6183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}