{"id":6232,"date":"2023-09-20T16:31:51","date_gmt":"2023-09-20T09:31:51","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=6232"},"modified":"2023-10-02T00:48:23","modified_gmt":"2023-10-01T17:48:23","slug":"%e0%b8%97%e0%b8%9a-%e0%b8%8b%e0%b8%b8%e0%b9%88%e0%b8%a1%e0%b9%80%e0%b8%87%e0%b8%b5%e0%b8%a2%e0%b8%9a-%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b1%e0%b8%9a","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/09\/20\/%e0%b8%97%e0%b8%9a-%e0%b8%8b%e0%b8%b8%e0%b9%88%e0%b8%a1%e0%b9%80%e0%b8%87%e0%b8%b5%e0%b8%a2%e0%b8%9a-%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b1%e0%b8%9a\/","title":{"rendered":"\u0e17\u0e1a.\u0e0b\u0e38\u0e48\u0e21\u0e40\u0e07\u0e35\u0e22\u0e1a \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e1c\u0e1a.\u0e17\u0e1a."},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/span><strong>\u00a0:<\/strong> 20 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566 \u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e01\u0e2d\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1a\u0e01 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25.\u0e2d.\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e08\u0e34\u0e15\u0e15\u0e4c\u0e41\u0e01\u0e49\u0e27\u0e41\u0e17\u0e49 \u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e0a\u0e31\u0e22 \u0e2b\u0e34\u0e19\u0e40\u0e18\u0e32\u0e27\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e34\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e34\u0e15\u0e15\u0e34\u0e02\u0e08\u0e23 \u0e0b\u0e36\u0e48\u0e07 \u0e1e\u0e25.\u0e2d.\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 3 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e \u0e14\u0e39\u0e41\u0e25\u0e0a\u0e32\u0e15\u0e34\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e25\u0e07\u0e19\u0e32\u0e21\u0e43\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e1b\u0e01\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e21\u0e38\u0e17\u0e34\u0e15\u0e32\u0e08\u0e34\u0e15<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1a\u0e01\u0e17\u0e31\u0e01\u0e17\u0e32\u0e22\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e0a\u0e31\u0e49\u0e19 4 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e21\u0e32\u0e16\u0e27\u0e32\u0e22\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 5 \u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e34\u0e15\u0e15\u0e34\u0e02\u0e08\u0e23 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e40\u0e1a\u0e19\u0e0b\u0e4c\u0e2a\u0e35\u0e1a\u0e23\u0e2d\u0e19\u0e0b\u0e4c\u0e40\u0e17\u0e32 \u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 1 \u0e01\u0e0d 5995 \u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e22\u0e39\u0e48 \u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e16\u0e27\u0e2a\u0e48\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07-\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1a\u0e01\u0e07\u0e14\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e27\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e08\u0e32\u0e01\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e1e\u0e25.\u0e2d.\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c \u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e19\u0e32\u0e22\u0e17\u0e2b\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e16\u0e27\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c (\u0e2d\u0e31\u0e15\u0e23\u0e32 \u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e1e\u0e34\u0e40\u0e28\u0e29) \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01.\u0e22. \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e34\u0e08\u0e08\u0e32\u0e19\u0e38\u0e40\u0e1a\u0e01\u0e29\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e01.\u0e22. \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e22\u0e31\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e01.\u0e22. \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e21\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e34\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e32\u0e22\u0e1e\u0e25\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e32\u0e22\u0e38\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e0b\u0e31\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e17\u0e31\u0e1e\u0e2d\u0e37\u0e48\u0e19\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e01.\u0e22. \u0e42\u0e14\u0e22\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e44\u0e17\u0e22 \u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25.\u0e2d.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e2d.\u0e17\u0e23\u0e07\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e2b\u0e19\u0e38\u0e19\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e40\u0e27\u0e25\u0e32 15.00 \u0e19. \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25.\u0e23.\u0e2d.\u0e40\u0e0a\u0e34\u0e07\u0e0a\u0e32\u0e22 \u0e0a\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e23.\u0e2d.\u0e2d\u0e30\u0e14\u0e38\u0e07 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e14\u0e34\u0e21 \u0e40\u0e27\u0e25\u0e32 14.00 \u0e19. \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25.\u0e2d.\u0e2d.\u0e2d\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e13\u0e13\u0e23\u0e16 \u0e01\u0e31\u0e1a \u0e1e\u0e25.\u0e2d.\u0e2d.\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1b\u0e34\u0e14\u0e19\u0e48\u0e32\u0e19\u0e1f\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e41\u0e25\u0e30 27 \u0e01.\u0e22. \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0b\u0e31\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b8%94%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%9a%e0%b8%b5%e0%b9%89%e0%b8%a2%e0%b8%95%e0%b8%b4%e0%b8%94%e0%b8%aa%e0%b8%9b%e0%b8%b5%e0%b8%94\/september600x800\/\" rel=\"attachment wp-att-6064\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6064\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/09\/september600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[41,37],"tags":[],"class_list":["post-6232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-37"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=6232"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6232\/revisions"}],"predecessor-version":[{"id":6234,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6232\/revisions\/6234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/6233"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=6232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=6232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=6232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}