{"id":6719,"date":"2023-11-26T13:22:40","date_gmt":"2023-11-26T06:22:40","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=6719"},"modified":"2023-12-03T08:23:07","modified_gmt":"2023-12-03T01:23:07","slug":"%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1-%e0%b8%a7%e0%b8%ad%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2023\/11\/26\/%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1-%e0%b8%a7%e0%b8%ad%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c\/","title":{"rendered":"\u201c\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21\u201d \u0e27\u0e2d\u0e19\u0e04\u0e19\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e27\u0e2d\u0e25\u0e40\u0e25\u0e47\u0e15 \u0e21\u0e2d\u0e07\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><span style=\"color: #333399;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 <\/strong><\/span>: 26 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2566\u00a0<strong>\u0e19\u0e32\u0e22\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e27\u0e0a\u0e22\u0e0a\u0e31\u0e22<\/strong> \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e23\u0e48\u0e32\u0e07 \u0e1e.\u0e23.\u0e1a \u0e01\u0e39\u0e49\u0e40\u0e07\u0e34\u0e19 5 \u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32 \u0e27\u0e48\u0e32 \u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e23\u0e39\u0e49\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e04\u0e07\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e16\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e01\u0e47\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e40\u0e23\u0e47\u0e27 \u0e01\u0e47\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e44\u0e17\u0e21\u0e4c\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1d\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c \u0e27\u0e48\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e41\u0e08\u0e01\u0e40\u0e07\u0e34\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e27\u0e48\u0e32 \u0e1e.\u0e23.\u0e1a.\u0e01\u0e39\u0e49\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e08\u0e30\u0e1c\u0e48\u0e32\u0e19 3 \u0e14\u0e48\u0e32\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e17\u0e31\u0e49\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32 \u0e2a\u0e20\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23 \u0e41\u0e25\u0e30 \u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e2b\u0e32\u0e01\u0e21\u0e35\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e32\u0e22\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e39\u0e01\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35\u0e01\u0e34\u0e19\u0e14\u0e35 \u0e41\u0e25\u0e30 \u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e19\u0e36\u0e07\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e04\u0e30\u0e04\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e34\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e14\u0e27\u0e07\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e2b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e04\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19<\/span><\/p>\n<p><span style=\"color: #333399;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2023\/10\/01\/%e0%b8%9c%e0%b8%9a-%e0%b8%95%e0%b8%a3-%e0%b8%aa%e0%b8%b1%e0%b9%88%e0%b8%87%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%97%e0%b8%b8%e0%b8%81%e0%b8%ab%e0%b8%99%e0%b9%88%e0%b8%a7%e0%b8%a2\/attachment\/172\/\" rel=\"attachment wp-att-6311\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6311\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/10\/172.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/10\/172.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/10\/172-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2023\/10\/172-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-6719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=6719"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6719\/revisions"}],"predecessor-version":[{"id":6721,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/6719\/revisions\/6721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/6720"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=6719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=6719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=6719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}