{"id":7400,"date":"2024-05-02T07:57:50","date_gmt":"2024-05-02T00:57:50","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=7400"},"modified":"2024-05-07T10:53:36","modified_gmt":"2024-05-07T03:53:36","slug":"%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%ad%e0%b8%b8%e0%b8%95%e0%b8%b8%e0%b8%af%e0%b9%80%e0%b8%95%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%9e%e0%b8%b2%e0%b8%a2%e0%b8%b8%e0%b8%a4%e0%b8%94%e0%b8%b9%e0%b8%a3%e0%b9%89","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2024\/05\/02\/%e0%b8%81%e0%b8%a3%e0%b8%a1%e0%b8%ad%e0%b8%b8%e0%b8%95%e0%b8%b8%e0%b8%af%e0%b9%80%e0%b8%95%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%9e%e0%b8%b2%e0%b8%a2%e0%b8%b8%e0%b8%a4%e0%b8%94%e0%b8%b9%e0%b8%a3%e0%b9%89\/","title":{"rendered":"\u0e01\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e38\u0e2f\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1e\u0e32\u0e22\u0e38\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19-\u0e1d\u0e19\u0e16\u0e25\u0e48\u0e21\u0e2b\u0e25\u0e32\u0e22\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e2b\u0e19\u0e37\u0e2d-\u0e2d\u0e35\u0e2a\u0e32\u0e19-\u0e01\u0e25\u0e32\u0e07 3-7 \u0e1e.\u0e04.\u0e19\u0e35\u0e49"},"content":{"rendered":"<h3 id=\":r1b:\" class=\"html-h3 xe8uvvx x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz x1gslohp x1yc453h\"><span class=\"xt0psk2\" style=\"color: #0000ff;\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv xzsf02u x1s688f\" style=\"color: #0000ff;\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZU6ou7WP39_NRFJAaECaH9DHVhQtjt-ZmK6H9QOKGQAx8azusKxpykkUiL5FHsTd22wrLtlJq4CoUkRA6HS1WP9ms0pU8ITB0L0RqFyzKcwFs1p12uvgKHVzKNLEnCuAMOlMX8cILYaku7rOWhWX9VlZD6sB-r2Iva1dWKxJjkz_moPqskJN0iOymLqtI3Ksgnr-W2lsMAvBdLHREqayk2j&amp;__tn__=-UC%2CP-R\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/strong><\/a><\/span> : 2 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567 \u0e01\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e38\u0e2f \u0e2d\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e15\u0e37\u0e2d\u0e19 \u0e1e\u0e32\u0e22\u0e38\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 3 \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a 3-7 \u0e1e.\u0e04.67 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1d\u0e19\u0e1f\u0e49\u0e32\u0e04\u0e30\u0e19\u0e2d\u0e07 \u0e25\u0e21\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e41\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e25\u0e39\u0e01\u0e40\u0e2b\u0e47\u0e1a\u0e15\u0e01\u0e1a\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07<\/h3>\n<p><span style=\"font-size: 16px;\">\u0e01\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e38\u0e19\u0e34\u0e22\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e2d\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e32\u0e22\u0e38\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 3 \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3-7 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3\u20135 \u0e1e.\u0e04. 67 \u0e04\u0e25\u0e37\u0e48\u0e19\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e25\u0e21\u0e1d\u0e48\u0e32\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e21\u0e35\u0e22\u0e19\u0e21\u0e32\u0e08\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e15\u0e2d\u0e19\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6-7 \u0e1e.\u0e04. 67 \u0e08\u0e30\u0e21\u0e35\u0e41\u0e19\u0e27\u0e1e\u0e31\u0e14\u0e2a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e25\u0e21\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e25\u0e21\u0e43\u0e15\u0e49\u0e1e\u0e31\u0e14\u0e1b\u0e01\u0e04\u0e25\u0e38\u0e21\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e15\u0e2d\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e31\u0e14 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e35\u0e1e\u0e32\u0e22\u0e38\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e1e\u0e32\u0e22\u0e38\u0e1d\u0e19\u0e1f\u0e49\u0e32\u0e04\u0e30\u0e19\u0e2d\u0e07 \u0e25\u0e21\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e41\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e25\u0e39\u0e01\u0e40\u0e2b\u0e47\u0e1a\u0e15\u0e01\u0e1a\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e1f\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19\u0e23\u0e30\u0e27\u0e31\u0e07\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1e\u0e32\u0e22\u0e38\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e17\u0e35\u0e48\u0e42\u0e25\u0e48\u0e07\u0e41\u0e08\u0e49\u0e07 \u0e43\u0e15\u0e49\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e04\u0e27\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e27\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e21\u0e35\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/span><\/p>\n<p><strong><span style=\"font-size: 16px;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3 \u2013 4 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567<\/span><\/strong><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e25\u0e33\u0e1e\u0e39\u0e19 \u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e19\u0e48\u0e32\u0e19 \u0e41\u0e1e\u0e23\u0e48 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u0e15\u0e32\u0e01 \u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e25\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e22\u0e42\u0e2a\u0e18\u0e23 \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07 : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35<\/span><\/p>\n<p><strong><span style=\"font-size: 16px;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u2013 6 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567<\/span><\/strong><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e25\u0e33\u0e1e\u0e39\u0e19 \u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e19\u0e48\u0e32\u0e19 \u0e41\u0e1e\u0e23\u0e48 \u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u0e15\u0e32\u0e01 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e25\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e22\u0e42\u0e2a\u0e18\u0e23 \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07 : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e32\u0e14<\/span><\/p>\n<p><strong><span style=\"font-size: 16px;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 7 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567<\/span><\/strong><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e25\u0e33\u0e1e\u0e39\u0e19 \u0e15\u0e32\u0e01 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07 : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 : \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e32\u0e14<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2024\/04\/01\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af%e0%b9%81%e0%b8%99%e0%b8%b0%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9e%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%b2\/attachment\/111\/\" rel=\"attachment wp-att-7299\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-7299\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/04\/111.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/04\/111.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/04\/111-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/04\/111-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-7400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=7400"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7400\/revisions"}],"predecessor-version":[{"id":7402,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7400\/revisions\/7402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/7401"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=7400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=7400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=7400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}