{"id":7664,"date":"2024-06-09T23:08:48","date_gmt":"2024-06-09T16:08:48","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=7664"},"modified":"2024-06-16T22:53:40","modified_gmt":"2024-06-16T15:53:40","slug":"%e0%b8%99%e0%b8%b4%e0%b8%94%e0%b9%89%e0%b8%b2%e0%b9%82%e0%b8%9e%e0%b8%a5%e0%b9%80%e0%b8%9c%e0%b8%a2-%e0%b8%9b%e0%b8%8a%e0%b8%8a-%e0%b8%aa%e0%b9%88%e0%b8%a7%e0%b8%99%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2024\/06\/09\/%e0%b8%99%e0%b8%b4%e0%b8%94%e0%b9%89%e0%b8%b2%e0%b9%82%e0%b8%9e%e0%b8%a5%e0%b9%80%e0%b8%9c%e0%b8%a2-%e0%b8%9b%e0%b8%8a%e0%b8%8a-%e0%b8%aa%e0%b9%88%e0%b8%a7%e0%b8%99%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88\/","title":{"rendered":"\u0e19\u0e34\u0e14\u0e49\u0e32\u0e42\u0e1e\u0e25\u0e40\u0e1c\u0e22 \u0e1b\u0e0a\u0e0a.\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e21\u0e48\u0e1e\u0e2d\u0e43\u0e08\u0e1c\u0e25\u0e07\u0e32\u0e19 9 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32"},"content":{"rendered":"<h3 id=\":r1b:\" class=\"html-h3 xe8uvvx x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz x1gslohp x1yc453h\"><span class=\"xt0psk2\" style=\"color: #0000ff;\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 xzsf02u x1s688f\" style=\"color: #0000ff;\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZU20icZhPOITg_IgkuXCwHTBq3B5SA-mTU3pqBnOL8CrUBZEQ0Uy5EXQ0cRhxbVreTp-Pcrqs8hrBZdrbsIFF1mEVVpyu0nF62BW_v0DwkI8rRZ0ULFvbwYn4BbkU5n6jmnR2okGbrlbsFFCbxJwII7zXtmfjEV2JeCeGa6H0_TFq1ixPGRhDCkEEHpzj6FJeA6GR3nkfrC5KHEHmeRWW0g&amp;__tn__=-UC%2CP-R\"><strong><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 <\/span><\/strong><\/a><\/span>: 9 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2567 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e19\u0e34\u0e14\u0e49\u0e32\u0e42\u0e1e\u0e25 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e1c\u0e25\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e1e\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e21\u0e48\u0e1e\u0e2d\u0e43\u0e08\u0e1c\u0e25\u0e07\u0e32\u0e19 9 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u201c\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u201d<\/h3>\n<p><span style=\"font-size: 16px;\">\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e43\u0e19\u0e23\u0e2d\u0e1a 9 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 34.35 \u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e1e\u0e2d\u0e43\u0e08 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 31.69 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e1e\u0e2d\u0e43\u0e08\u0e40\u0e25\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e44\u0e27\u0e49 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 25.19 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e1e\u0e2d\u0e43\u0e08 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 7.40 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e1e\u0e2d\u0e43\u0e08\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 35.95 \u0e44\u0e21\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e40\u0e25\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e14 \u0e46 \u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 35.04 \u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49 \u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e21\u0e48\u0e15\u0e23\u0e07\u0e08\u0e38\u0e14 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 22.14 \u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 5.42 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e17\u0e27\u0e35\u0e2a\u0e34\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 2 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43.44 \u0e19\u0e32\u0e22\u0e01\u0e2f \u0e40\u0e28\u0e23\u0e29\u0e10\u0e32 \u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 15.65 \u0e1e\u0e23\u0e23\u0e04\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 15.50 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 10.92 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e22\u0e38\u0e1a\u0e2a\u0e20\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 10.46 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 6.56 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e04\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 6.11 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e25\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 4.58 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e04\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 3.21 \u0e2a\u0e2a. \u0e1d\u0e48\u0e32\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 3.05 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 2.60 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30 \u0e2a\u0e2a. \u0e1d\u0e48\u0e32\u0e22\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e08\u0e30\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e25\u0e14\u0e25\u0e07 \u0e43\u0e19\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%a1%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7%e0%b9%88\/600x800-18\/\" rel=\"attachment wp-att-7534\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-7534\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/05\/600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/05\/600x800.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/05\/600x800-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/05\/600x800-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-7664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=7664"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7664\/revisions"}],"predecessor-version":[{"id":7666,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/7664\/revisions\/7666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/7665"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=7664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=7664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=7664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}