{"id":8100,"date":"2024-08-24T22:00:11","date_gmt":"2024-08-24T15:00:11","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=8100"},"modified":"2024-09-04T13:23:35","modified_gmt":"2024-09-04T06:23:35","slug":"%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b9%81%e0%b8%9a%e0%b8%87%e0%b8%81%e0%b9%8c%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4-%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%97%e0%b8%b3","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2024\/08\/24\/%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%a7%e0%b9%88%e0%b8%b2%e0%b9%81%e0%b8%9a%e0%b8%87%e0%b8%81%e0%b9%8c%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4-%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%97%e0%b8%b3\/","title":{"rendered":"\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e41\u0e1a\u0e07\u0e01\u0e4c\u0e0a\u0e32\u0e15\u0e34 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25-\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e04\u0e19\u0e25\u0e30\u0e43\u0e1a \u0e43\u0e0a\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49"},"content":{"rendered":"<h3 id=\":r1l:\" class=\"html-h3 x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz x1gslohp x1yc453h\"><span class=\"xt0psk2\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 xzsf02u x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZVJMIFmDUmY0FWaU28_IN1anRRlMvn91b8qbqV8X7vFfgAT0L_0eC1eOUyvo16mlgtNDLVeXKLrslPaJ-t6TlGqnb1cNBCYn4_5R-MuCaAvLlUx2Mqi0BcGYj8eN7auAYwI1PysVkyQ3F8bQ_BOW4yqo3s9eSdRxK7reCMGe0wcngzqpWuJJLYslzzYGG8ngqABnCQTaJQDWNPzgNORjXbq&amp;__tn__=-UC%2CP-R\"><strong class=\"html-strong xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x1s688f\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span style=\"color: #0000ff;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/span><\/strong><\/a><\/span> : 24 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2567\u00a0\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e41\u0e1a\u0e07\u0e01\u0e4c\u0e0a\u0e32\u0e15\u0e34 \u0e22\u0e31\u0e19\u0e44\u0e21\u0e48\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e2b\u0e32\u0e01\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e15\u0e36\u0e07\u0e15\u0e31\u0e27\u0e21\u0e32\u0e01\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e1b\u0e31\u0e14\u0e15\u0e2d\u0e1a\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e40\u0e02\u0e49\u0e32 FIDF<\/h3>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e40\u0e28\u0e23\u0e29\u0e10\u0e1e\u0e38\u0e12\u0e34 \u0e2a\u0e38\u0e17\u0e18\u0e34\u0e27\u0e32\u0e17\u0e19\u0e24\u0e1e\u0e38\u0e12\u0e34<\/strong> \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 (\u0e01\u0e19\u0e07.) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d 21 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2567 \u0e43\u0e2b\u0e49\u0e04\u0e07\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e35\u0e48 2.50% \u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e02\u0e2d\u0e07 \u0e01\u0e19\u0e07. \u0e21\u0e32\u0e08\u0e32\u0e01 3 \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e40\u0e07\u0e34\u0e19\u0e40\u0e1f\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e41\u0e15\u0e48\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e33 \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 2 \u0e1b\u0e35 2567 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1f\u0e49\u0e2d \u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e23\u0e2d\u0e1a\u0e25\u0e48\u0e32\u0e07 1-3 % \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e27\u0e30\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e37\u0e14 \u0e41\u0e15\u0e48\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07\u0e02\u0e31\u0e49\u0e19\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e27\u0e30\u0e15\u0e36\u0e07\u0e15\u0e31\u0e27\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e0b\u0e36\u0e48\u0e07 \u0e18\u0e1b\u0e17. \u0e08\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e01\u0e47\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1b \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e36\u0e07\u0e15\u0e31\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e02\u0e2d\u0e22\u0e49\u0e33\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e01\u0e19\u0e07.\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e08\u0e30\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e40\u0e07\u0e34\u0e19\u0e40\u0e1f\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e44\u0e27\u0e49 \u0e01\u0e47\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e40\u0e23\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e16\u0e25\u0e07\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07 \u0e01\u0e19\u0e07. \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e48\u0e27\u0e07\u0e43\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u201d \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2f \u0e18\u0e1b\u0e17. \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e18\u0e1b\u0e17. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e27\u0e48\u0e32 \u0e18\u0e1b\u0e17. \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e13\u0e30\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e21\u0e32\u0e42\u0e14\u0e22\u0e15\u0e25\u0e2d\u0e14 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2d\u0e2d\u0e01\u0e2a\u0e39\u0e48\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e41\u0e15\u0e48\u0e04\u0e19\u0e44\u0e1b\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e21\u0e2b\u0e21\u0e27\u0e01\u0e04\u0e19\u0e25\u0e30\u0e43\u0e1a \u0e18\u0e1b\u0e17. \u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e2b\u0e23\u0e31\u0e10 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1f\u0e14 \u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1f\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e44\u0e27\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e01\u0e14\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e25\u0e14\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e15\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e18\u0e1b\u0e17. \u0e22\u0e49\u0e33\u0e27\u0e48\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e17\u0e35\u0e48\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e25\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23 \u0e2d\u0e14\u0e35\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e08\u0e48\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d FIDF \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e32\u0e01 \u0e23\u0e27\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 0.46-0.47% \u0e25\u0e07\u0e04\u0e23\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e2b\u0e25\u0e37\u0e2d 0.23% \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32 \u0e18\u0e1b\u0e17. \u0e23\u0e30\u0e1a\u0e38\u0e22\u0e31\u0e07\u0e40\u0e23\u0e47\u0e27\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e15\u0e2d\u0e1a<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e35 \u0e40\u0e08\u0e29\u0e0e\u0e32\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23 \u0e2a\u0e32\u0e22\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e18\u0e1b\u0e17. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e40\u0e07\u0e34\u0e19\u0e40\u0e02\u0e49\u0e32\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 FIDF 0.46% \u0e01\u0e47\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1.6 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e08\u0e32\u0e01\u0e22\u0e2d\u0e14\u0e40\u0e07\u0e34\u0e19\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 5.8 \u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d 5.5 \u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e40\u0e07\u0e34\u0e19\u0e40\u0e02\u0e49\u0e32\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e25\u0e07\u0e44\u0e1b\u0e04\u0e23\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 5 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e22\u0e2d\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e07\u0e04\u0e49\u0e32\u0e07\u0e2b\u0e21\u0e14\u0e0a\u0e49\u0e32\u0e25\u0e07<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2024\/08\/16\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a0%e0%b8%b2-%e0%b8%99%e0%b8%b3%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad-%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%98\/1019-%e0%b9%84%e0%b8%ae%e0%b9%84%e0%b8%a5%e0%b8%97%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b8%ad%e0%b8%87\/\" rel=\"attachment wp-att-8053\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-8053\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/08\/1019-\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07.jpg\" alt=\"\" width=\"601\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/08\/1019-\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07.jpg 601w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/08\/1019-\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/08\/1019-\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07-585x779.jpg 585w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-8100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=8100"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8100\/revisions"}],"predecessor-version":[{"id":8102,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8100\/revisions\/8102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/8101"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=8100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=8100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=8100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}