{"id":8823,"date":"2025-01-03T23:29:09","date_gmt":"2025-01-03T16:29:09","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=8823"},"modified":"2025-01-16T05:25:19","modified_gmt":"2025-01-15T22:25:19","slug":"%e0%b8%99%e0%b8%9e%e0%b8%94%e0%b8%a5-%e0%b8%a1%e0%b8%b1%e0%b9%88%e0%b8%99%e0%b9%83%e0%b8%88%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%99-mou44-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9a%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/01\/03\/%e0%b8%99%e0%b8%9e%e0%b8%94%e0%b8%a5-%e0%b8%a1%e0%b8%b1%e0%b9%88%e0%b8%99%e0%b9%83%e0%b8%88%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%99-mou44-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9a%e0%b8%b2\/","title":{"rendered":"\u201c\u0e19\u0e1e\u0e14\u0e25\u201d \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e04\u0e49\u0e32\u0e19 MOU44 \u0e44\u0e21\u0e48\u0e1a\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e02\u0e2d\u0e04\u0e38\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25"},"content":{"rendered":"<h3 id=\":rik:\" class=\"html-h3 x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz x1gslohp x1yc453h\"><span class=\"xt0psk2\" style=\"color: #0000ff;\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 xzsf02u x1s688f\" style=\"color: #0000ff;\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZUJG6uBA_0soD5rqwE4GOXZwtldJ2LPNGK_pM0qx6LowAfIgD_pKWML1SdzTtdZJz29cH9-SzB8ZT276ow93EMG_bDyvt6TS28DXNvNhRDFxmimQJgrYXTv1PHJcjO0RVgcHxcejEe_sjk-33cJM2Np&amp;__tn__=-UC%2CP-R\"><strong class=\"html-strong xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x1s688f\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/strong><\/a><\/span> : 3 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2568 \u201c\u0e19\u0e1e\u0e14\u0e25\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e04\u0e49\u0e32\u0e19 MOU 44 \u0e44\u0e21\u0e48\u0e1a\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e02\u0e2d\u0e04\u0e38\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 \u0e2d\u0e22\u0e48\u0e32\u0e14\u0e49\u0e2d\u0e22\u0e04\u0e48\u0e32\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e19\u0e30\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e08\u0e38\u0e14\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e40\u0e02\u0e32\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e17\u0e47\u0e08\u0e41\u0e25\u0e30\u0e27\u0e32\u0e17\u0e30\u0e01\u0e23\u0e23\u0e21\u0e25\u0e27\u0e07\u0e43\u0e2a\u0e48\u0e23\u0e49\u0e32\u0e22\u0e15\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27<\/h3>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e19\u0e1e\u0e14\u0e25 \u0e1b\u0e31\u0e17\u0e21\u0e30<\/strong> \u0e2a\u0e2a.\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e2d\u0e14\u0e35\u0e15\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e1b\u0e35 2568 \u0e27\u0e48\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e41\u0e23\u0e01 \u0e01\u0e47\u0e04\u0e07\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e2d\u0e20\u0e34\u0e1b\u0e23\u0e32\u0e22\u0e44\u0e21\u0e48\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e19\u00a0 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e19\u0e32\u0e22\u0e01\u0e2f\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e21\u0e32\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e20\u0e34\u0e1b\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e20\u0e32 \u0e16\u0e49\u0e32\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e43\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e01\u0e47\u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e01\u0e31\u0e07\u0e27\u0e25 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e04\u0e49\u0e32\u0e19 MOU 44 \u0e02\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e19\u0e33\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e40\u0e14\u0e34\u0e21\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e15\u0e48\u0e15\u0e19\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e17\u0e48\u0e32\u0e17\u0e35\u0e02\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e19\u0e33\u0e1c\u0e39\u0e49\u0e04\u0e31\u0e14\u0e04\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32\u0e19\u0e32\u0e22\u0e1b\u0e32\u0e19\u0e40\u0e17\u0e1e \u0e1e\u0e31\u0e27\u0e1e\u0e07\u0e29\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21\u0e17\u0e35\u0e48\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e14\u0e49\u0e2d\u0e22\u0e04\u0e48\u0e32\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e27\u0e48\u0e32\u0e40\u0e1e\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1e\u0e25\u0e49\u0e33\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e21\u0e23\u0e21\u0e32\u0e42\u0e14\u0e22\u0e15\u0e25\u0e2d\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e0a\u0e19\u0e30\u0e2a\u0e15\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e19\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e31\u0e28\u0e19\u0e04\u0e15\u0e34\u0e14\u0e39\u0e41\u0e04\u0e25\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1e\u0e32\u0e14\u0e1e\u0e34\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e07\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32\u0e21\u0e32\u0e15\u0e2d\u0e1a\u0e42\u0e15\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e14\u0e22\u0e21\u0e32\u0e23\u0e22\u0e32\u0e17\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e39\u0e15 \u0e40\u0e02\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e1b\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e27\u0e48\u0e32\u0e15\u0e19\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e08\u0e32\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u00a0 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e39\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e31\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e2a\u0e15\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e25\u0e30\u0e21\u0e32\u0e23\u0e22\u0e32\u0e17\u00a0 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e02\u0e32\u0e14\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e22\u0e01\u0e15\u0e19\u0e02\u0e48\u0e21\u0e17\u0e48\u0e32\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e19\u0e1e\u0e14\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e2d\u0e31\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e43\u0e19\u0e1b\u0e35 2549 \u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e44\u0e14\u0e49\u0e22\u0e37\u0e48\u0e19 1) \u0e15\u0e31\u0e27\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 2) \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e1a\u0e15\u0e31\u0e27\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e44\u0e1b\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u00a0 \u0e41\u0e15\u0e48\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e21\u0e31\u0e22\u0e1c\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e08\u0e23\u0e08\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e08\u0e19\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e22\u0e2d\u0e21\u0e15\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e17\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u00a0 \u0e41\u0e25\u0e30\u0e22\u0e2d\u0e21\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e31\u0e27\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e15\u0e48\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e19\u0e32\u0e22\u0e2a\u0e19\u0e18\u0e34 \u0e25\u0e34\u0e49\u0e21\u0e17\u0e2d\u0e07\u0e01\u0e38\u0e25 \u0e41\u0e25\u0e30\u0e41\u0e01\u0e19\u0e19\u0e33\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e49\u0e19\u00a0 \u0e42\u0e08\u0e21\u0e15\u0e35\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2b\u0e32\u0e43\u0e2a\u0e48\u0e23\u0e49\u0e32\u0e22\u0e15\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e17\u0e47\u0e08\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e19\u0e44\u0e14\u0e49\u0e25\u0e07\u0e19\u0e32\u0e21\u0e43\u0e19\u0e04\u0e33\u0e41\u0e16\u0e25\u0e07\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e44\u0e17\u0e22-\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e19\u0e31\u0e49\u0e19\u00a0 1) \u0e15\u0e19\u0e44\u0e14\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19 2)\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e27\u0e07\u0e04\u0e37\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23\u00a0 3) \u0e1e\u0e27\u0e01\u0e15\u0e19\u0e02\u0e32\u0e22\u0e0a\u0e32\u0e15\u0e34 4) \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e23\u0e2d\u0e1a\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e19\u0e33\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e32\u0e1c\u0e34\u0e14\u0e15\u0e19\u0e15\u0e48\u0e2d \u0e1b\u0e1b\u0e0a \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e21\u0e32 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e1b\u0e1b\u0e0a.\u0e44\u0e1b\u0e22\u0e37\u0e48\u0e19\u0e1f\u0e49\u0e2d\u0e07\u0e15\u0e19\u0e15\u0e48\u0e2d\u0e28\u0e32\u0e25\u0e0e\u0e35\u0e01\u0e32\u0e41\u0e1c\u0e19\u0e01\u0e04\u0e14\u0e35\u0e2d\u0e32\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2558 \u0e04\u0e14\u0e35\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e41\u0e14\u0e07\u0e17\u0e35\u0e48 \u0e2d\u0e21. 63\/ 2558 \u0e28\u0e32\u0e25\u0e0e\u0e35\u0e01\u0e32\u0e2f\u0e44\u0e14\u0e49\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32\u0e22\u0e01\u0e1f\u0e49\u0e2d\u0e07\u0e15\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e04\u0e33\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e43\u0e19\u0e04\u0e33\u0e41\u0e16\u0e25\u0e07\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e44\u0e17\u0e22-\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32 \u0e02\u0e2d\u0e07\u0e08\u0e33\u0e40\u0e25\u0e22 (\u0e19\u0e32\u0e22\u0e19\u0e1e\u0e14\u0e25) \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e36\u0e07\u0e2a\u0e21\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e01\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e27\u0e07\u0e04\u0e37\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u00a0 \u0e44\u0e17\u0e22\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e43\u0e19\u0e04\u0e33\u0e41\u0e16\u0e25\u0e07\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e48\u0e27\u0e21<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2b\u0e32 4 \u0e02\u0e49\u0e2d\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e43\u0e2a\u0e48\u0e23\u0e49\u0e32\u0e22\u0e1c\u0e21\u0e19\u0e31\u0e49\u0e19\u0e40\u0e17\u0e47\u0e08\u0e41\u0e25\u0e30\u0e1c\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e1b\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e33\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e34\u0e08\u0e08\u0e32\u0e19\u0e38\u0e40\u0e1a\u0e01\u0e29\u0e32 \u0e40\u0e25\u0e48\u0e21 132 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 111\u0e01 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2558 \u0e15\u0e19\u0e08\u0e36\u0e07\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e04\u0e49\u0e32\u0e19 mou 44 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u00a0 \u0e04\u0e27\u0e23\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2a\u0e48\u0e23\u0e49\u0e32\u0e22\u0e40\u0e17\u0e47\u0e08\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e1e\u0e23\u0e30\u0e27\u0e34\u0e2b\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e07\u00a0 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e22\u0e31\u0e07\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32 mou 44 \u0e44\u0e1b\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e27\u0e35\u0e1b\u0e02\u0e2d\u0e07 \u0e01\u0e1e\u0e0a \u0e41\u0e25\u0e30\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e46\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e2a\u0e19\u0e18\u0e34\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e2f\u0e1a\u0e2d\u0e01\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e14\u0e49\u0e2d\u0e22\u0e04\u0e48\u0e32\u0e40\u0e02\u0e32\u0e2d\u0e35\u0e01 \u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e04\u0e23\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e04\u0e23\u0e31\u0e1a\u201d \u0e19\u0e32\u0e22\u0e19\u0e1e\u0e14\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/%e0%b9%81%e0%b8%88%e0%b8%81%e0%b8%aa%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b7%e0%b8%ad%e0%b8%99-%e0%b9%80%e0%b8%ae%e0%b8%87%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%97%e0%b9%89%e0%b8%b2%e0%b8%a2%e0%b8%9b%e0%b8%b5\/05_highlight-politics-600x800-2\/\" rel=\"attachment wp-att-8711\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-8711\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/12\/05_HIGHLIGHT-POLITICS-600x800-1.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/12\/05_HIGHLIGHT-POLITICS-600x800-1.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/12\/05_HIGHLIGHT-POLITICS-600x800-1-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2024\/12\/05_HIGHLIGHT-POLITICS-600x800-1-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-8823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=8823"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8823\/revisions"}],"predecessor-version":[{"id":8825,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/8823\/revisions\/8825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/8824"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=8823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=8823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=8823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}