{"id":9165,"date":"2025-04-28T09:06:35","date_gmt":"2025-04-28T02:06:35","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=9165"},"modified":"2025-05-04T09:54:59","modified_gmt":"2025-05-04T02:54:59","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a2%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%94%e0%b8%b1%e0%b8%9a-%e0%b8%aa%e0%b8%81%e0%b8%a5%e0%b8%99%e0%b8%84%e0%b8%a3-%e0%b8%99%e0%b8%84","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/04\/28\/%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a2%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%94%e0%b8%b1%e0%b8%9a-%e0%b8%aa%e0%b8%81%e0%b8%a5%e0%b8%99%e0%b8%84%e0%b8%a3-%e0%b8%99%e0%b8%84\/","title":{"rendered":"\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u201c\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23-\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21-\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\u201d \u0e2a\u0e39\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08-\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e19\u0e38\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07"},"content":{"rendered":"<h3 id=\"\u00abr10\u00bb\" class=\"html-h3 x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz x1gslohp x1yc453h\"><span class=\"xt0psk2\"><span class=\"xjp7ctv\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj xzsf02u x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZUn7rL7O3XD-lFNGF4x8HXFQqckxRk_2S8CFxzGPj0jEULALsnndlm6z--1m4QMkxxe2N_n0Oukuum6SRkV3cYweQeZehf9XtI7TnVUHry9R_4z9F0cvmC_tj8DbsyHvJMpvuYE12fRTfTeM6UNi3EcqGE3xicN2sD0is86P7aEmulOeDmpyVJVEHYvtjgmyNs&amp;__tn__=-UC%2CP-R\"><strong class=\"html-strong xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x1s688f\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span style=\"color: #0000ff;\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/span><\/strong><\/a><\/span><\/span> <strong>: <\/strong><strong>28 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2568 <\/strong>\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u201c\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23-\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21-\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\u201d \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e19\u0e38\u0e01 \u0e2a\u0e39\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e19\u0e38\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 \u0e40\u0e1c\u0e22\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21-\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3>\n<p><span style=\"font-size: 16px;\"><strong>\u0e19\u0e32\u0e22\u0e08\u0e34\u0e23\u0e32\u0e22\u0e38 \u0e2b\u0e48\u0e27\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c<\/strong> \u0e42\u0e06\u0e29\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e35 2568 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e2d\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u201d \u0e17\u0e31\u0e48\u0e27\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e19 3 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e04\u0e37\u0e2d\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0b\u0e2d\u0e1f\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e0a\u0e39\u0e42\u0e23\u0e07 3 \u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e2d\u0e01\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e2d\u0e31\u0e19\u0e07\u0e14\u0e07\u0e32\u0e21 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u201c\u0e44\u0e2b\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1f\u201d \u0e2a\u0e39\u0e48\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1f\u0e42\u0e25\u0e01 \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e0a\u0e32\u0e27\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e41\u0e2b\u0e48\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1c\u0e36\u0e49\u0e07 \u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e02\u0e35\u0e49\u0e1c\u0e36\u0e49\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e41\u0e02\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e27\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e41\u0e02\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e27\u0e2d\u0e2d\u0e01\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e42\u0e02\u0e07 \u0e44\u0e17\u0e22 &#8211; \u0e2a\u0e1b\u0e1b.\u0e25\u0e32\u0e27 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e19\u0e32\u0e22\u0e08\u0e34\u0e23\u0e32\u0e22\u0e38 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e19\u0e38\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e21\u0e34\u0e15\u0e34 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/span><\/p>\n<p><span style=\"font-size: 16px;\">1.\u0e01\u0e32\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e21\u0e32\u0e22\u0e31\u0e07\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\u0e41\u0e25\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e43\u0e19\u0e1b\u0e35 2568<\/span><\/p>\n<p><span style=\"font-size: 16px;\">2.\u0e01\u0e32\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e17\u0e32\u0e07\u0e04\u0e39\u0e48\u0e2a\u0e32\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e0a\u0e48\u0e27\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e1c\u0e48 &#8211; \u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 &#8211; \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07 355 \u0e01\u0e21. \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1b\u0e35 2571 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 3.8 \u0e25\u0e49\u0e32\u0e19\u0e04\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e35\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e27\u0e48\u0e32 700,000 \u0e15\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 3 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e37\u0e2d \u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 &#8211; \u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 &#8211; \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07 247 \u0e01\u0e21. \u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 &#8211; \u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c &#8211; \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07 316 \u0e01\u0e21. \u0e0a\u0e48\u0e27\u0e07\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 &#8211; \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d &#8211; \u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07 173 \u0e01\u0e21. \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1b\u0e35 2568 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 R12 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e44\u0e17\u0e22 \u0e2a\u0e1b\u0e1b.\u0e25\u0e32\u0e27 \u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21\u0e41\u0e25\u0e30\u0e08\u0e35\u0e19\u0e15\u0e2d\u0e19\u0e43\u0e15\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a One Stop Service<\/span><\/p>\n<p><span style=\"font-size: 16px;\">3.\u0e01\u0e32\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2b\u0e25\u0e32\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e2d\u0e35\u0e01\u0e01\u0e27\u0e48\u0e32 20 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u201c\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e15\u0e2d\u0e19\u0e1a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a \u0e41\u0e25\u0e30\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u201d \u0e19\u0e32\u0e22\u0e08\u0e34\u0e23\u0e32\u0e22\u0e38\u0e22\u0e49\u0e33<\/span><\/p>\n<p><span style=\"color: #0000ff;\">Advertisement<\/span><\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/05_highlight-politics-600x800-3\/\" rel=\"attachment wp-att-9127\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9127\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/04\/05_HIGHLIGHT-POLITICS-600x800-1.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/04\/05_HIGHLIGHT-POLITICS-600x800-1.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/04\/05_HIGHLIGHT-POLITICS-600x800-1-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/04\/05_HIGHLIGHT-POLITICS-600x800-1-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-9165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=9165"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9165\/revisions"}],"predecessor-version":[{"id":9167,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9165\/revisions\/9167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/9166"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=9165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=9165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=9165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}