{"id":9355,"date":"2025-05-25T15:39:26","date_gmt":"2025-05-25T08:39:26","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=9355"},"modified":"2025-06-18T10:22:34","modified_gmt":"2025-06-18T03:22:34","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af-%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%97%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b4%e0%b8%93-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/05\/25\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af-%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%97%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b4%e0%b8%93-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%94\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e22\u0e31\u0e19 \u201c\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13\u201d \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e19\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e28\u0e32\u0e25 13 \u0e21\u0e34.\u0e22."},"content":{"rendered":"<p><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 : 25 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2568\u00a0\u201c\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u201d \u0e22\u0e31\u0e19 \u201c\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13\u201d \u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e49\u0e32 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e44\u0e2b\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e28\u0e32\u0e25 13 \u0e21\u0e34.\u0e22.\u0e19\u0e35\u0e49 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u201c\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e39\u0e25\u0e32 1\u201d \u0e43\u0e19\u0e44\u0e17\u0e22\u0e21\u0e35\u0e2b\u0e27\u0e31\u0e07 \u0e02\u0e2d\u0e23\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 2-3 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/strong><\/p>\n<p><strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23<\/strong> \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 46 \u0e17\u0e35\u0e48\u0e01\u0e23\u0e38\u0e07\u0e01\u0e31\u0e27\u0e25\u0e32\u0e25\u0e31\u0e21\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22 \u0e16\u0e36\u0e07\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e28\u0e32\u0e25\u0e0e\u0e35\u0e01\u0e32\u0e41\u0e1c\u0e19\u0e01\u0e04\u0e14\u0e35\u0e2d\u0e32\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e19\u0e31\u0e14\u0e44\u0e15\u0e48\u0e2a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23 \u0e2d\u0e14\u0e35\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e23\u0e27\u0e08 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e21\u0e34.\u0e22.68 \u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e43\u0e08 \u0e41\u0e15\u0e48\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e34\u0e14\u0e2d\u0e30\u0e44\u0e23<\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e14\u0e23\u0e32\u0e21\u0e32\u0e27\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e22\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e2d\u0e1a\u0e27\u0e48\u0e32 \u0e22\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e48\u0e30 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e01\u0e04\u0e23\u0e39\u0e48\u0e22\u0e31\u0e07\u0e42\u0e17\u0e23\u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32 \u0e2b\u0e25\u0e31\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e23\u0e32\u0e0a\u0e23\u0e31\u0e10\u0e42\u0e21\u0e19\u0e32\u0e42\u0e01 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e17\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e22\u0e31\u0e07\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e22\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e49\u0e32\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e44\u0e2b\u0e19\u0e40\u0e25\u0e22<\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e44\u0e1b\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e14\u0e39\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e25\u0e49\u0e27\u0e04\u0e48\u0e30 \u0e16\u0e49\u0e32\u0e44\u0e1b \u0e44\u0e1b\u0e14\u0e39\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e39\u0e01\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u201d<\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e40\u0e08\u0e2d\u0e14\u0e23\u0e32\u0e21\u0e32\u0e2b\u0e19\u0e31\u0e01\u0e46 \u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e21\u0e32\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e40\u0e25\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e14\u0e23\u0e32\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23 \u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e01\u0e47\u0e41\u0e04\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e47\u0e15\u0e41\u0e25\u0e47\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e2b\u0e19\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e08\u0e30\u0e44\u0e1b\u0e02\u0e36\u0e49\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e2d \u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e04\u0e34\u0e14\u0e21\u0e32\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22 \u0e16\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e21\u0e48\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e2b\u0e19\u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e32\u0e15\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e2d\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e22\u0e31\u0e07\u0e15\u0e2d\u0e1a\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e47\u0e08\u0e30\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e15\u0e2d\u0e1a\u0e43\u0e2b\u0e49 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e30\u0e44\u0e23<\/p>\n<p>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e44\u0e1b\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e2b\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e04\u0e33\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e32\u0e01 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e27\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e1b\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e15\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e25\u0e2d\u0e19\u0e14\u0e2d\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e44\u0e1b\u0e04\u0e38\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e27\u0e48\u0e32\u0e17\u0e33 FTA \u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e43\u0e19\u0e25\u0e2d\u0e19\u0e14\u0e2d\u0e19\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e01\u0e47\u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e43\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e42\u0e21\u0e19\u0e32\u0e42\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e44\u0e1b\u0e04\u0e38\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 F1 \u0e41\u0e25\u0e30\u0e44\u0e1b\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1d\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e2d\u0e31\u0e25\u0e41\u0e1a\u0e23\u0e4c\u0e17\u0e35\u0e48 2 \u0e41\u0e2b\u0e48\u0e07\u0e23\u0e32\u0e0a\u0e23\u0e31\u0e10\u0e42\u0e21\u0e19\u0e32\u0e42\u0e01 \u0e2a\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e2a\u0e01\u0e1c\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49<\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e37\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e39\u0e25\u0e32 1 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e44\u0e14\u0e49\u0e02\u0e49\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23 \u0e41\u0e15\u0e48\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2-3 \u0e40\u0e14\u0e37\u0e2d\u0e19.<\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/2025\/06\/08\/%e0%b9%82%e0%b8%86%e0%b8%a9%e0%b8%81%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b1%e0%b8%9e%e0%b9%84%e0%b8%97%e0%b8%a2-%e0%b8%ad%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a1%e0%b8%9c%e0%b8%b9\/470-5\/\" rel=\"attachment wp-att-9313\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9313\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/06\/470.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/06\/470.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/06\/470-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/06\/470-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-9355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=9355"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9355\/revisions"}],"predecessor-version":[{"id":9356,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9355\/revisions\/9356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/9173"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=9355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=9355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=9355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}