{"id":9595,"date":"2025-07-17T22:51:15","date_gmt":"2025-07-17T15:51:15","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=9595"},"modified":"2025-08-04T07:40:32","modified_gmt":"2025-08-04T00:40:32","slug":"%e0%b8%97%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b0%e0%b9%80%e0%b8%82%e0%b8%b7%e0%b8%ad-%e0%b9%84%e0%b8%a1","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/07\/17\/%e0%b8%97%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a2%e0%b8%b1%e0%b8%99-%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b0%e0%b9%80%e0%b8%82%e0%b8%b7%e0%b8%ad-%e0%b9%84%e0%b8%a1\/","title":{"rendered":"\u0e17\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e22\u0e31\u0e19 \u201c\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u201d \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e22\u0e36\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27 \u0e22\u0e49\u0e33\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1b\u0e01\u0e15\u0e34"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong><span style=\"color: #0000ff;\"><a class=\"x1i10hfl xjbqb8w x1ejq31n x18oe1m7 x1sy0etr xstzfhl x972fbf x10w94by x1qhh985 x14e42zd x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj xzsf02u x1s688f\" style=\"color: #0000ff;\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/politicaffair?__cft__[0]=AZUJP527p57kRsYio6foEmWf2i02I1VUU0izPW6Y4YLNAi4AhJGjUTjj8r9K5lQaDWsYKsWfyab3JcD6jYFlx2ELFq64ITnTPWMlZXhti8QK5AEqJCm6B6WlA2eCLFFb5w3Nin3kTRmYgbOx5E6NLcnkeYE_s5Cb9_YQZkOoMCL2dDK2g3WCM42Vqzb5rKFeBxo&amp;__tn__=-UC%2CP-R\"><span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07<\/span><\/a> <\/span>: 17 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2568\u00a0\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48 1 \u0e01\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e35 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e04\u0e38\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u201c\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u201d \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e22\u0e36\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e43\u0e19\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22 \u0e22\u0e49\u0e33\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1b\u0e01\u0e15\u0e34 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e08\u0e07\u0e1b\u0e21\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32\u0e02\u0e36\u0e49\u0e19\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d \u0e41\u0e04\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e01\u0e23\u0e2d\u0e01\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e41\u0e15\u0e48\u0e17\u0e2b\u0e32\u0e23\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e40\u0e17\u0e49\u0e32<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e02\u0e48\u0e32\u0e27\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e16\u0e39\u0e01\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e22\u0e36\u0e14 <strong>\u0e1e.\u0e17.\u0e08\u0e31\u0e01\u0e23\u0e01\u0e24\u0e29\u0e13\u0e4c<\/strong> <strong>\u0e02\u0e38\u0e23\u0e34\u0e23\u0e31\u0e07<\/strong> \u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e01\u0e2d\u0e07\u0e1e\u0e31\u0e19\u0e17\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e1a\u0e17\u0e35\u0e48 11 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48 1 \u0e01\u0e2d\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d \u0e21\u0e35\u0e17\u0e2b\u0e32\u0e23\u0e27\u0e32\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e41\u0e19\u0e27 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e30\u0e44\u0e23<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e1a\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e08\u0e38\u0e14\u0e15\u0e23\u0e27\u0e08 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e49\u0e21\u0e35\u0e08\u0e38\u0e14\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e10\u0e32\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e36\u0e07\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1d\u0e48\u0e32\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e32\u0e14\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e1a\u0e1b\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e44\u0e14\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1c\u0e34\u0e14\u0e19\u0e31\u0e49\u0e19 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e35\u0e49 \u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1e.\u0e17.\u0e08\u0e31\u0e01\u0e23\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e22\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07 \u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e02\u0e36\u0e49\u0e19\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e01\u0e14\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e1b\u0e35 2551-2552 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e16\u0e49\u0e32\u0e08\u0e30\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1d\u0e48\u0e32\u0e22\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e23\u0e2b\u0e32 \u0e17\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e19\u0e31\u0e49\u0e19 \u0e1e.\u0e17.\u0e08\u0e31\u0e01\u0e23\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e17\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e32\u0e14\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1c\u0e34\u0e14\u0e1b\u0e01\u0e15\u0e34\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e17\u0e49\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e01\u0e47\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e1a\u0e19\u0e20\u0e39\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d \u0e17\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e25\u0e32\u0e14\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e2b\u0e32\u0e23\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e25\u0e32\u0e14\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/span><\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/to.gsb.or.th\/GflibL7g\" rel=\"attachment wp-att-9588\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9588\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/07\/723.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/07\/723.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/07\/723-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/07\/723-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[41,37],"tags":[],"class_list":["post-9595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-37"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=9595"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9595\/revisions"}],"predecessor-version":[{"id":9597,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9595\/revisions\/9597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/9596"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=9595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=9595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=9595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}