{"id":9759,"date":"2025-08-28T04:20:07","date_gmt":"2025-08-27T21:20:07","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=9759"},"modified":"2025-09-04T08:11:11","modified_gmt":"2025-09-04T01:11:11","slug":"%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b9%82%e0%b8%9e%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%81%e0%b8%a5%e0%b8%b2%e0%b8%87%e0%b8%95%e0%b8%b6%e0%b8%81%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%84%e0%b8%b9","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/08\/28\/%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b9%82%e0%b8%9e%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%81%e0%b8%a5%e0%b8%b2%e0%b8%87%e0%b8%95%e0%b8%b6%e0%b8%81%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%84%e0%b8%b9\/","title":{"rendered":"\u0e08\u0e31\u0e14\u0e42\u0e1e\u0e40\u0e14\u0e35\u0e22\u0e21\u0e01\u0e25\u0e32\u0e07\u0e15\u0e36\u0e01\u0e44\u0e17\u0e22\u0e04\u0e39\u0e48\u0e1f\u0e49\u0e32 \u0e23\u0e2d\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e41\u0e16\u0e25\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e28\u0e32\u0e25\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22"},"content":{"rendered":"<p><span style=\"font-size: 16px;\"><strong>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 28 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568\u00a0\u0e08\u0e31\u0e14\u0e42\u0e1e\u0e40\u0e14\u0e35\u0e22\u0e21\u0e01\u0e25\u0e32\u0e07\u0e15\u0e36\u0e01\u0e44\u0e17\u0e22\u0e04\u0e39\u0e48\u0e1f\u0e49\u0e32\u0e23\u0e2d \u201c\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u201d \u0e19\u0e32\u0e22\u0e01\u0e2f \u0e41\u0e16\u0e25\u0e07 \u0e2b\u0e25\u0e31\u0e07\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e1b\u0e21\u0e04\u0e25\u0e34\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e19\u0e17\u0e19\u0e32 \u201c\u0e2e\u0e38\u0e19\u0e40\u0e0b\u0e19\u201d<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e1c\u0e39\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e2a.\u0e04.\u0e19\u0e35\u0e49 \u0e19.\u0e2a.\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e17\u0e35\u0e21\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e25\u0e30 \u0e19\u0e1e.\u0e1e\u0e23\u0e2b\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e25\u0e34\u0e28\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e4c\u0e40\u0e14\u0e0a \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e04\u0e14\u0e35\u0e04\u0e25\u0e34\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e19\u0e17\u0e19\u0e32 \u201c\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e2e\u0e38\u0e19 \u0e40\u0e0b\u0e19\u201d \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 \u0e19.\u0e2a.\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 14.00 \u0e19. \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e31\u0e49\u0e19 2 \u0e15\u0e36\u0e01\u0e44\u0e17\u0e22\u0e04\u0e39\u0e48\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e35\u0e21\u0e48\u0e27\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e17\u0e35\u0e48\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08 \u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19<\/span><\/p>\n<p><span style=\"font-size: 16px;\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2b\u0e25\u0e31\u0e07\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e19\u0e32\u0e22\u0e01\u0e2f \u0e08\u0e30\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e16\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e15\u0e36\u0e01\u0e44\u0e17\u0e22\u0e04\u0e39\u0e48\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e43\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e0b\u0e31\u0e01\u0e16\u0e32\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2f \u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e27\u0e48\u0e32 \u0e19.\u0e2a.\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e2a\u0e2a. \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e2a\u0e2a.\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e08\u0e30\u0e44\u0e1b\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e40\u0e01\u0e32\u0e30\u0e15\u0e34\u0e14\u0e1c\u0e25\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e22\u0e31\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22<\/span><\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/874-3\/\" rel=\"attachment wp-att-9723\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9723\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[37,38],"tags":[],"class_list":["post-9759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-38"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=9759"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9759\/revisions"}],"predecessor-version":[{"id":9760,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9759\/revisions\/9760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/9761"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=9759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=9759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=9759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}