{"id":9838,"date":"2025-09-25T09:36:36","date_gmt":"2025-09-25T02:36:36","guid":{"rendered":"https:\/\/www.highlightpolitics.com\/index\/?p=9838"},"modified":"2025-10-07T22:39:22","modified_gmt":"2025-10-07T15:39:22","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af%e0%b9%80%e0%b8%a2%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b8%a5%e0%b8%b2%e0%b8%94%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2-%e0%b8%aa%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.highlightpolitics.com\/index\/2025\/09\/25\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%af%e0%b9%80%e0%b8%a2%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b8%a5%e0%b8%b2%e0%b8%94%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2-%e0%b8%aa%e0%b8%a3\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e01\u0e2f\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e17\u0e22 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"},"content":{"rendered":"<p>\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e1e\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e17\u0e22\u0e0a\u0e37\u0e48\u0e19\u0e21\u0e37\u0e48\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e30\u0e14\u0e21\u0e17\u0e38\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p><strong>\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e0a\u0e32\u0e0d\u0e27\u0e35\u0e23\u0e01\u0e39\u0e25<\/strong> \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e19\u0e34\u0e15\u0e34 \u0e19\u0e34\u0e15\u0e34\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e28 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e19\u0e32\u0e07\u0e28\u0e38\u0e20\u0e08\u0e35 \u0e2a\u0e38\u0e18\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e19\u0e32\u0e22\u0e2d\u0e23\u0e23\u0e16\u0e1e\u0e25 \u0e24\u0e01\u0e29\u0e4c\u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e27\u0e23\u0e20\u0e31\u0e04 \u0e18\u0e31\u0e19\u0e22\u0e32\u0e27\u0e07\u0e29\u0e4c \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e17\u0e22 (FETCO) \u0e43\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d \u201c\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e08\u0e32\u0e01\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u201d<\/p>\n<p>\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19\u200b \u0e01\u0e25\u0e48\u0e32\u0e27\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e48\u0e32\u200b \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e21\u0e32\u0e1e\u0e1a\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u200b \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e19\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e2b\u0e25\u0e31\u0e1a\u200b \u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 09.00 \u0e19. \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e14\u0e35\u200b \u200b\u0e08\u0e30\u0e44\u0e14\u0e49\u0e21\u0e32\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23\u200b\u0e17\u0e35\u0e48\u0e14\u0e35\u200b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e27\u0e31\u0e07\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32\u200b \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e47\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e01\u0e47\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u200b \u0e41\u0e21\u0e49\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u200b \u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19\u200b \u0e41\u0e15\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e01\u0e47\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e19\u0e17\u0e38\u0e01\u0e17\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u200b<\/p>\n<p>\u201c\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e30\u0e14\u0e21\u0e17\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e44\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u200b \u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e2b\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u201d \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e17\u0e34\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<p>Advertisement<\/p>\n<p><a href=\"https:\/\/www.highlightpolitics.com\/index\/home\/874-3\/\" rel=\"attachment wp-att-9723\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9723\" src=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874.jpg 600w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874-225x300.jpg 225w, https:\/\/www.highlightpolitics.com\/index\/wp-content\/uploads\/2025\/08\/874-585x780.jpg 585w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e1e\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[48],"tags":[],"class_list":["post-9838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-48"],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/comments?post=9838"}],"version-history":[{"count":1,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9838\/revisions"}],"predecessor-version":[{"id":9840,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts\/9838\/revisions\/9840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media\/9839"}],"wp:attachment":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/media?parent=9838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/categories?post=9838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags?post=9838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}