{"id":155,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%95%e0%b8%a3%e0%b8%b5\/","name":"\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a3%e0%b8%b1%e0%b8%90%e0%b8%a1%e0%b8%99%e0%b8%95%e0%b8%a3%e0%b8%b5","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}