{"id":291,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b8%99%e0%b8%b2%e0%b9%81%e0%b8%9b%e0%b8%a5%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88\/","name":"\u0e19\u0e32\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48","slug":"%e0%b8%99%e0%b8%b2%e0%b9%81%e0%b8%9b%e0%b8%a5%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%8d%e0%b9%88","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}