{"id":424,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b8%a3%e0%b8%b1%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a5%e0%b8%97%e0%b8%b5%e0%b9%88-9\/","name":"\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a5%e0%b8%97%e0%b8%b5%e0%b9%88-9","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}