{"id":450,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b8%aa%e0%b8%b5-%e0%b8%88%e0%b8%b4%e0%b9%89%e0%b8%99-%e0%b8%9c%e0%b8%b4%e0%b8%87\/","name":"\u0e2a\u0e35 \u0e08\u0e34\u0e49\u0e19 \u0e1c\u0e34\u0e07","slug":"%e0%b8%aa%e0%b8%b5-%e0%b8%88%e0%b8%b4%e0%b9%89%e0%b8%99-%e0%b8%9c%e0%b8%b4%e0%b8%87","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}