{"id":459,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b8%aa%e0%b8%a1%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b8%a2%e0%b8%a3%e0%b8%95%e0%b8%b4-%e0%b8%81%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%a7%e0%b8%ab%e0%b8%b2\/","name":"\u0e2a\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e01\u0e34\u0e21\u0e32\u0e27\u0e2b\u0e32","slug":"%e0%b8%aa%e0%b8%a1%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b8%a2%e0%b8%a3%e0%b8%95%e0%b8%b4-%e0%b8%81%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%a7%e0%b8%ab%e0%b8%b2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}