{"id":89,"count":1,"description":"","link":"https:\/\/www.highlightpolitics.com\/index\/tag\/%e0%b9%82%e0%b8%84%e0%b8%a7%e0%b8%b4%e0%b8%94-19-2\/","name":"\u0e42\u0e04\u0e27\u0e34\u0e14 - 19","slug":"%e0%b9%82%e0%b8%84%e0%b8%a7%e0%b8%b4%e0%b8%94-19-2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.highlightpolitics.com\/index\/wp-json\/wp\/v2\/posts?tags=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}